{"id":10817,"date":"2024-07-30T00:34:44","date_gmt":"2024-07-30T04:34:44","guid":{"rendered":"https:\/\/www.ciudadgoticanews.com\/?p=10817"},"modified":"2024-08-03T05:40:57","modified_gmt":"2024-08-03T09:40:57","slug":"escandalo-colombia-nene-hernandez-vicente-rujano","status":"publish","type":"post","link":"https:\/\/www.ciudadgoticanews.com\/index.php\/2024\/07\/30\/escandalo-colombia-nene-hernandez-vicente-rujano\/","title":{"rendered":"\u00a1Esc\u00e1ndalo! La sombra narcoganadera de \u00ab\u00d1e\u00f1e\u00bb Hern\u00e1ndez se cierne sobre los negocios del venezolano Vicente Rujano Gar\u00f3falo en Colombia, Venezuela y Estados Unidos"},"content":{"rendered":"<p>En el turbulento mundo de los negocios, las fortunas opacas y los v\u00ednculos con el narcotr\u00e1fico, en ocasiones, van de la mano. Un caso que despierta interrogantes y alimenta rumores es el de la familia Rujano Gar\u00f3falo, originaria del estado T\u00e1chira en Venezuela. Si bien gozan de una posici\u00f3n econ\u00f3mica privilegiada, con empresas e inversiones que se extienden m\u00e1s all\u00e1 de las fronteras venezolanas, algunas voces susurran que su ascenso mete\u00f3rico podr\u00eda estar ligado al extinto narcotraficante colombiano Jos\u00e9 Guillermo Hern\u00e1ndez Aponte, alias \u201c\u00d1e\u00f1e\u201d Hern\u00e1ndez.<\/p>\n<p>En el ojo del hurac\u00e1n se encuentra Vicente Rujano Gar\u00f3falo, quien ha tejido una compleja red empresarial que ha llamado la atenci\u00f3n de algunos. Una de sus primeras incursiones en el mundo empresarial fue a trav\u00e9s de Inversiones Ganapanam. Esta empresa, seg\u00fan fuentes consultadas, fue objeto en Venezuela de investigaciones por parte de la Comisi\u00f3n Nacional de Administraci\u00f3n de Divisas (CADIVI), por el manejo de 14 millones de d\u00f3lares que recibi\u00f3 en el a\u00f1o 2014. Ese mismo a\u00f1o, el Centro Nacional de Comercio Exterior (CENCOEX), entidad estatal otrora encargada del otorgamiento de Divisas preferenciales y sucesora de CADIVI, coloc\u00f3 bajo la lupa a Importaciones Ganapanam C.A. como parte de una supervisi\u00f3n regular a empresas que se beneficiaron de divisas preferenciales.<\/p>\n<p>La familia Rujano Gar\u00f3falo, un apellido que resuena en el ambiente empresarial del T\u00e1chira, no solo destaca por sus negocios en Venezuela, sino tambi\u00e9n por su presencia en la vecina Colombia. Su influencia se extiende al manejo del matadero de reses en La Fr\u00eda, una ciudad fronteriza que abastece tanto al mercado venezolano como al colombiano.<\/p>\n<figure id=\"attachment_10832\" aria-describedby=\"caption-attachment-10832\" style=\"width: 1200px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2023\/07\/gisela-garofalo-waldo-rujano.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-10832\" src=\"https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2023\/07\/gisela-garofalo-waldo-rujano.jpg\" alt=\"\" width=\"1200\" height=\"600\" srcset=\"https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2023\/07\/gisela-garofalo-waldo-rujano.jpg 1200w, https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2023\/07\/gisela-garofalo-waldo-rujano-300x150.jpg 300w, https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2023\/07\/gisela-garofalo-waldo-rujano-1024x512.jpg 1024w, https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2023\/07\/gisela-garofalo-waldo-rujano-768x384.jpg 768w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><\/a><figcaption id=\"caption-attachment-10832\" class=\"wp-caption-text\">Gisela Gar\u00f3falo de Rujano y Waldo Rujano<\/figcaption><\/figure>\n<p>El patriarca de la familia, Waldo Rujano Mora, junto a su esposa Gisela Gar\u00f3falo Contreras, han visto crecer el imperio familiar. Andrea Rujano Gar\u00f3falo, hermana de Vicente y m\u00e9dico esteticista, tambi\u00e9n juega un papel importante en los negocios familiares. Su cl\u00ednica de trasplante capilar, \u00abCapil Clinic\u00bb, ubicada en la capital tachirense, San Crist\u00f3bal, es solo una muestra de la diversificaci\u00f3n de sus intereses.<\/p>\n<figure id=\"attachment_10829\" aria-describedby=\"caption-attachment-10829\" style=\"width: 1200px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2023\/07\/andrea-rujano.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-10829\" src=\"https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2023\/07\/andrea-rujano.jpg\" alt=\"\" width=\"1200\" height=\"600\" srcset=\"https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2023\/07\/andrea-rujano.jpg 1200w, https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2023\/07\/andrea-rujano-300x150.jpg 300w, https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2023\/07\/andrea-rujano-1024x512.jpg 1024w, https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2023\/07\/andrea-rujano-768x384.jpg 768w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><\/a><figcaption id=\"caption-attachment-10829\" class=\"wp-caption-text\">Andrea Rujano<\/figcaption><\/figure>\n<h3>V\u00ednculos opacos y un imperio trasatl\u00e1ntico<\/h3>\n<p>Las habladur\u00edas en los mentideros tachirenses y colombianos se\u00f1alan a Jos\u00e9 \u201c\u00d1e\u00f1e\u201d Hern\u00e1ndez, controvertido narcotraficante colombiano, como el posible origen de parte de la bonanza econ\u00f3mica de los Rujano Gar\u00f3falo. Hern\u00e1ndez, quien tambi\u00e9n manten\u00eda nexos con el narcotraficante Marquitos Figueroa, encontr\u00f3 un tr\u00e1gico final en mayo de 2019 cuando fue asesinado en Brasil, durante un supuesto robo. Sin embargo, la sombra de la duda se cierne sobre este suceso, debido a la larga lista de enemigos que Hern\u00e1ndez acumul\u00f3 a lo largo de su turbia trayectoria.<\/p>\n<figure id=\"attachment_10890\" aria-describedby=\"caption-attachment-10890\" style=\"width: 1200px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2023\/07\/vicente-rujano004.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-10890\" src=\"https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2023\/07\/vicente-rujano004.jpg\" alt=\"\" width=\"1200\" height=\"600\" srcset=\"https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2023\/07\/vicente-rujano004.jpg 1200w, https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2023\/07\/vicente-rujano004-300x150.jpg 300w, https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2023\/07\/vicente-rujano004-1024x512.jpg 1024w, https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2023\/07\/vicente-rujano004-768x384.jpg 768w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><\/a><figcaption id=\"caption-attachment-10890\" class=\"wp-caption-text\">Vicente Rujano<\/figcaption><\/figure>\n<p>Curiosamente, la familia Rujano Gar\u00f3falo posee la Finca Villa Cecilia, en Piedecuesta, municipio colombiano situado a pocos kil\u00f3metros de Bucaramanga, en el departamento de Santander. Esta localidad tambi\u00e9n albergaba una de las propiedades de Hern\u00e1ndez, quien ten\u00eda un especial inter\u00e9s en esta regi\u00f3n colombiana. Los rumores sobre una posible sociedad entre el narcotraficante y la familia venezolana se han extendido como la p\u00f3lvora, siendo alimentados por nuevas evidencias de la proximidad de los Rujano con \u00ab\u00d1e\u00f1e\u00bb Hern\u00e1ndez. La Finca Villa Cecilia, se ubica a cerca de 18 km al sureste de Bucaramanga.<\/p>\n<p>Para manejar sus asuntos financieros, la familia Rujano Gar\u00f3falo recurre a una testaferro conocida como \u00abYurley\u00bb, seg\u00fan indican antiguos moradores de Bucaramanga. Este personaje opera como el rostro visible de algunos negocios, mientras los verdaderos propietarios permanecen en la sombra. Se presume que estas actividades esconden un sofisticado esquema financiero, con cuentas bancarias en Panam\u00e1, espec\u00edficamente en las entidades bancarias Banesco Panam\u00e1 y Mercantil Banco Panam\u00e1.<\/p>\n<p>La ambici\u00f3n de Vicente Rujano Gar\u00f3falo lo ha llevado a traspasar fronteras. Entre 2013 y 2019, junto a su padre Waldo, su hermana Andrea y el abogado venezolano Germ\u00e1n De Jes\u00fas Rinc\u00f3n Montilla, oriundo del estado T\u00e1chira, registr\u00f3 alrededor de 60 empresas en Florida, Estados Unidos. Entre estas compa\u00f1\u00edas figuran R&amp;R Global Services Corp, Capacho Llc, Helechales Llc, Chururu Llc, Andrevi Corp, Abejales Llc, Minka Holdings 1 Llc, Rodecia Investments Llc, R&amp;R Pet Foods Corp, Potreros Llc y Lagrita Llc. Resulta llamativo que varias de las empresas, como Capacho Llc, Orope Llc, Lagrita Llc o Bocono Llc, entre otras, llevan nombres que evocan localidades del estado T\u00e1chira o estados vecinos.<\/p>\n<h3>Un imperio inmobiliario bajo la lupa<\/h3>\n<p>El rastro de los Rujano Gar\u00f3falo en Florida no se limita a empresas de papel. Alrededor de 30 de las compa\u00f1\u00edas registradas por Vicente Rujano entre 2014 y 2016, con nombres como 21329 Nw Llc, 13464 Sw 27 St Corp o 3069 Nw 204 Ln Llc, parecen estar vinculadas a propiedades inmobiliarias en la ciudad de Miramar y otras zonas de Florida. La constituci\u00f3n de esas firmas coincide con la \u00e9poca en la que los Rujano Gar\u00f3falo recibieron en Venezuela divisas preferenciales del CENCOEX.<\/p>\n<p>Es conocido que en Venezuela, extintos organismos cambiarios, como el CENCOEX o CADIVI, fueron foco de corrupci\u00f3n, y que las divisas a tasa preferencial que otorgaron a empresas y particulares, con el fin de la importaci\u00f3n de bienes o el pago de servicios, terminaron en muchos casos siendo desviadas para otros prop\u00f3sitos, justific\u00e1ndose mediante documentos que certificaban importaciones que en realidad no se realizaron o que hab\u00edan sido sobrefacturadas.<\/p>\n<p>Fuentes del sector inmobiliario estadounidense estiman que la familia Rujano Gar\u00f3falo posee m\u00e1s de un centenar de inmuebles en territorio estadounidense, la mayor\u00eda destinados al alquiler.<\/p>\n<p>La madrugada del 12 de octubre de 2016, Waldo Rujano, el patriarca familiar, fue detenido en Miramar, Florida, por conducir bajo los efectos del alcohol. La Oficina del Sheriff del Condado de Broward le impuso una fianza, y el 6 de octubre de 2017 fue sentenciado a seis meses de libertad condicional, pena que cumpli\u00f3 en abril de 2018.<\/p>\n<figure id=\"attachment_10877\" aria-describedby=\"caption-attachment-10877\" style=\"width: 1200px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2023\/07\/waldo-rujano-arresto2016.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-10877\" src=\"https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2023\/07\/waldo-rujano-arresto2016.jpg\" alt=\"\" width=\"1200\" height=\"486\" srcset=\"https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2023\/07\/waldo-rujano-arresto2016.jpg 1200w, https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2023\/07\/waldo-rujano-arresto2016-300x122.jpg 300w, https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2023\/07\/waldo-rujano-arresto2016-1024x415.jpg 1024w, https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2023\/07\/waldo-rujano-arresto2016-768x311.jpg 768w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><\/a><figcaption id=\"caption-attachment-10877\" class=\"wp-caption-text\">Reporte de arresto de Waldo Rujano en 2016, en Miramar, Florida, por conducir bajo los efectos del alcohol<\/figcaption><\/figure>\n<p>La presencia de la familia Rujano Gar\u00f3falo en Florida se extiende m\u00e1s all\u00e1 de Vicente y su padre. Su esposa, Greidaly Rubio Jurado, tambi\u00e9n figura en algunas de las empresas registradas en el estado. Asimismo, Germ\u00e1n De Jes\u00fas Rinc\u00f3n Montilla, adem\u00e1s de socio, funge como una especie de administrador para las propiedades de la familia, encarg\u00e1ndose de la gesti\u00f3n administrativa y el mantenimiento de los inmuebles. La direcci\u00f3n de residencia de Germ\u00e1n Rinc\u00f3n Montilla en Miramar aparece asociada a algunas de las empresas de la familia Rujano Gar\u00f3falo, lo que sugiere una estrecha relaci\u00f3n entre ambos.<\/p>\n<figure id=\"attachment_10870\" aria-describedby=\"caption-attachment-10870\" style=\"width: 1200px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2023\/07\/Greidaly-Rubio.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-10870\" src=\"https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2023\/07\/Greidaly-Rubio.jpg\" alt=\"\" width=\"1200\" height=\"600\" srcset=\"https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2023\/07\/Greidaly-Rubio.jpg 1200w, https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2023\/07\/Greidaly-Rubio-300x150.jpg 300w, https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2023\/07\/Greidaly-Rubio-1024x512.jpg 1024w, https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2023\/07\/Greidaly-Rubio-768x384.jpg 768w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><\/a><figcaption id=\"caption-attachment-10870\" class=\"wp-caption-text\">Greidaly Rubio, esposa de Vicente Rujano.<\/figcaption><\/figure>\n<p>La red de colaboradores de la familia Rujano Gar\u00f3falo en Florida se extiende incluso a la esposa de Germ\u00e1n Rinc\u00f3n Montilla, la abogada venezolana Fanny Su\u00e1rez Prato. Tanto ella como su esposo han actuado como agentes residentes de algunas de las empresas de los Rujano, consolidando a\u00fan m\u00e1s los lazos entre ambas familias.<\/p>\n<p>Las actividades empresariales de la familia Rujano Gar\u00f3falo no se limitan al sector inmobiliario. En Venezuela, poseen alrededor de 10 fincas ganaderas que les generan importantes ingresos. Adem\u00e1s, son due\u00f1os de Disprogata C.A., una empresa ubicada en Coloncito, estado T\u00e1chira, que produce y exporta snacks para perros, elaborados con \u00f3rganos de res y cerdo. Sus productos, que llegan a puertos de Estados Unidos como Port Everglades en Fort Lauderdale, Florida, o incluso Texas y Nueva York, son comercializados a trav\u00e9s de R&amp;R Pet Foods Corp, otra empresa bajo el control de la familia Rujano.<\/p>\n<h3>M\u00e1s all\u00e1 de las sospechas: un v\u00ednculo innegable<\/h3>\n<p>Las especulaciones sobre la relaci\u00f3n de Vicente Rujano Gar\u00f3falo y su familia con el mundo del narcotr\u00e1fico colombiano trascienden los meros rumores. Fotograf\u00edas y un video, que expondremos m\u00e1s adelante, muestran la cercan\u00eda que mantuvieron los Rujano, no solo con \u201c\u00d1e\u00f1e\u201d Hern\u00e1ndez, sino que han mantenido tambi\u00e9n con la esposa del difunto ganadero, Mar\u00eda M\u00f3nica Urbina. Estas im\u00e1genes, pudieran arrojar luz sobre los negocios que se esconden tras la fortuna de la familia tachirense.<\/p>\n<p>Adicionalmente, antiguos vecinos del empresario en Venezuela aseguran que Vicente Rujano Gar\u00f3falo posee una propiedad en La Castellana, una exclusiva urbanizaci\u00f3n de San Crist\u00f3bal, estado T\u00e1chira.<\/p>\n<p>De igual manera, se ha detectado un creciente inter\u00e9s de Vicente Rujano Gar\u00f3falo por el continente europeo. Sus frecuentes viajes a Madrid, donde se hospeda por largas temporadas, sugieren que la familia podr\u00eda haber adquirido propiedades en Espa\u00f1a, utilizando fondos de origen dudoso. Sin embargo, el inter\u00e9s de Vicente Rujano por Espa\u00f1a parece tener tambi\u00e9n otra explicaci\u00f3n.<\/p>\n<h3>Las pasiones ocultas y no tanto de Vicente Rujano<\/h3>\n<p>En la vida, para Vicente Rujano son distintivas tres pasiones. Una es la ganader\u00eda, otra el gusto por la m\u00fasica, que lo llev\u00f3 hace m\u00e1s de una d\u00e9cada a querer contratar a los mejores acordeonistas colombianos para aprender a tocar el acorde\u00f3n, o a patrocinar a exponentes del vallenato solo para que lo mencionaran en el \u00ednterin de sus interpretaciones musicales. Y la tercera pasi\u00f3n de Rujano son las mujeres, que lo han llevado, antes y despu\u00e9s de estar casado, al punto tal de pagar lo que sea con tal de tener encuentros lujuriosos con exuberantes damas.<\/p>\n<p>Esa tercera pasi\u00f3n parece haber llevado a Rujano a entablar una relaci\u00f3n extramarital con Yessika Y\u00e9pez, una contadora p\u00fablica de T\u00e1chira y una influencer de fitness que no tiene reparos en exhibir su esbelta figura en las redes sociales. Y\u00e9pez, una venezolana que disfruta de la vida al m\u00e1ximo, se enorgullece de sus frecuentes viajes a Colombia, Espa\u00f1a, Italia, Francia y Estados Unidos, as\u00ed como de su rutina de gimnasio, sus caprichos, sus visitas a restaurantes, sus asistencias a conciertos y otros lujos que algunos sospechan son financiados por Rujano.<\/p>\n<figure id=\"attachment_10866\" aria-describedby=\"caption-attachment-10866\" style=\"width: 1200px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2023\/07\/Yessika-Yepez00.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-10866\" src=\"https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2023\/07\/Yessika-Yepez00.jpg\" alt=\"\" width=\"1200\" height=\"600\" srcset=\"https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2023\/07\/Yessika-Yepez00.jpg 1200w, https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2023\/07\/Yessika-Yepez00-300x150.jpg 300w, https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2023\/07\/Yessika-Yepez00-1024x512.jpg 1024w, https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2023\/07\/Yessika-Yepez00-768x384.jpg 768w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><\/a><figcaption id=\"caption-attachment-10866\" class=\"wp-caption-text\">Yessika Y\u00e9pez<\/figcaption><\/figure>\n<p>Los viajes de Y\u00e9pez a Espa\u00f1a, parecen explicar el inter\u00e9s que ha tenido Rujano, de pasar largas temporadas tambi\u00e9n en territorio espa\u00f1ol, tal parece que con el fin de mantenerse alejado, junto a Y\u00e9pez, de las miradas indiscretas en Venezuela o Colombia y as\u00ed poder continuar adelante la relaci\u00f3n entre ambos, mientras disfrutan de los placeres de la vida.<\/p>\n<figure id=\"attachment_10868\" aria-describedby=\"caption-attachment-10868\" style=\"width: 1200px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2023\/07\/Yessika-Yepez002.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-10868\" src=\"https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2023\/07\/Yessika-Yepez002.jpg\" alt=\"\" width=\"1200\" height=\"600\" srcset=\"https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2023\/07\/Yessika-Yepez002.jpg 1200w, https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2023\/07\/Yessika-Yepez002-300x150.jpg 300w, https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2023\/07\/Yessika-Yepez002-1024x512.jpg 1024w, https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2023\/07\/Yessika-Yepez002-768x384.jpg 768w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><\/a><figcaption id=\"caption-attachment-10868\" class=\"wp-caption-text\">Yessika Y\u00e9pez<\/figcaption><\/figure>\n<p>Seg\u00fan relatos de antiguos vecinos de San Crist\u00f3bal, Rujano ha llegado incluso a regalarle a su pareja extramarital una lujosa casa en esa ciudad, un gesto que habla vol\u00famenes de la profundidad de su inter\u00e9s por ella.<\/p>\n<h3>Un pasado como funcionario p\u00fablico sancionado administrativamente<\/h3>\n<p>Germ\u00e1n Rinc\u00f3n Montilla, quien, adem\u00e1s de socio, ejerce como una suerte de \u00abcommunity manager realtor\u00bb o gerente inmobiliario, para las propiedades de los Rujano Gar\u00f3falo en Florida, tiene un pasado pol\u00e9mico como otrora empleado de nivel medio de una entidad estatal en Venezuela.<\/p>\n<figure id=\"attachment_11024\" aria-describedby=\"caption-attachment-11024\" style=\"width: 1200px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2024\/07\/German-Rincon-Montilla-y-su-esposa-Fanny-Suarez-Prato002.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-11024\" src=\"https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2024\/07\/German-Rincon-Montilla-y-su-esposa-Fanny-Suarez-Prato002.jpg\" alt=\"\" width=\"1200\" height=\"600\" srcset=\"https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2024\/07\/German-Rincon-Montilla-y-su-esposa-Fanny-Suarez-Prato002.jpg 1200w, https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2024\/07\/German-Rincon-Montilla-y-su-esposa-Fanny-Suarez-Prato002-300x150.jpg 300w, https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2024\/07\/German-Rincon-Montilla-y-su-esposa-Fanny-Suarez-Prato002-1024x512.jpg 1024w, https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2024\/07\/German-Rincon-Montilla-y-su-esposa-Fanny-Suarez-Prato002-768x384.jpg 768w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><\/a><figcaption id=\"caption-attachment-11024\" class=\"wp-caption-text\">Germ\u00e1n Rinc\u00f3n Montilla y su esposa Fanny Su\u00e1rez Prato<\/figcaption><\/figure>\n<p>En el a\u00f1o 2005, la Contralor\u00eda General de Venezuela emiti\u00f3 una resoluci\u00f3n contra el abogado Germ\u00e1n de Jes\u00fas Rinc\u00f3n Montilla, quien fue sancionado por incurrir en pr\u00e1cticas irregulares durante su desempe\u00f1o como Adjunto al Consultor Jur\u00eddico en el Banco de Fomento Regional Los Andes (BANFOANDES)<\/p>\n<p>El punto central de la controversia se remontaba al ejercicio fiscal de 1999, cuando Rinc\u00f3n Montilla, ostentando el cargo de Adjunto al Consultor Jur\u00eddico de BANFOANDES, celebr\u00f3 un contrato con la misma instituci\u00f3n estatal para la que laboraba, para prestar servicios profesionales. Espec\u00edficamente, se le contrat\u00f3, de manera paralela, para la defensa del banco en un juicio por saneamiento iniciado por la sociedad mercantil T\u00e9cnicos de Concreto S.A. (TECONSA) el 26 de octubre de 1998.<\/p>\n<p>El contrato en cuesti\u00f3n, firmado el 25 de agosto de 1999, involucraba no solo a Rinc\u00f3n Montilla sino tambi\u00e9n a otros abogados. La Junta Directiva de BANFOANDES hab\u00eda aprobado esta contrataci\u00f3n mediante una resoluci\u00f3n fechada el 13 de agosto de 1999, estableciendo como honorarios un monto equivalente al cinco por ciento (5%) del valor de la demanda.<\/p>\n<p>La Contralor\u00eda General determin\u00f3 que esta contrataci\u00f3n violaba directamente el art\u00edculo 124 de la Constituci\u00f3n de la Rep\u00fablica vigente en ese momento, que prohib\u00eda expl\u00edcitamente a los funcionarios p\u00fablicos celebrar contratos con las entidades a las que serv\u00edan. Esta prohibici\u00f3n se mantuvo en el art\u00edculo 145 de la Constituci\u00f3n de 1999, reforzando la continuidad de este principio \u00e9tico en la administraci\u00f3n p\u00fablica venezolana.<\/p>\n<p>La conducta de Rinc\u00f3n Montilla fue considerada como una infracci\u00f3n al numeral 5 del art\u00edculo 113 de la Ley Org\u00e1nica de la Contralor\u00eda General de la Rep\u00fablica, vigente en el momento de los hechos. Posteriormente, esta infracci\u00f3n encontr\u00f3 su equivalente en el art\u00edculo 91, numeral 4, de la Ley Org\u00e1nica de la Contralor\u00eda General de la Rep\u00fablica y del Sistema Nacional de Control Fiscal.<\/p>\n<p>El 20 de diciembre de 2004, la Contralor\u00eda General declar\u00f3 la responsabilidad administrativa de Rinc\u00f3n Montilla. Esta decisi\u00f3n se bas\u00f3 en la evidencia de la contrataci\u00f3n irregular y la clara violaci\u00f3n de las disposiciones constitucionales y legales vigentes.<\/p>\n<p>Considerando la gravedad de la falta cometida y el da\u00f1o causado al patrimonio p\u00fablico, la Contralor\u00eda General resolvi\u00f3 imponer a Germ\u00e1n de Jes\u00fas Rinc\u00f3n Montilla una sanci\u00f3n de suspensi\u00f3n del ejercicio de cualquier cargo p\u00fablico por un per\u00edodo de seis meses, sin goce de sueldo.<\/p>\n<p>Tras la sanci\u00f3n, Rinc\u00f3n Montilla y su esposa, Fanny Su\u00e1rez Prato, estuvieron dedicados, en conjunto, al libre ejercicio del derecho en el estado T\u00e1chira.<\/p>\n<p>El abogado Germ\u00e1n De Jes\u00fas Rinc\u00f3n, quien cuenta con ciudadan\u00eda estadounidense, adem\u00e1s, es quien se encarga de recibir en los Estados Unidos, fondos enviados por los Rujano Gar\u00f3falo desde Panam\u00e1, y de canalizar otros fondos de la familia Rujano entre Suiza y Estados Unidos.<\/p>\n<h3>\u00bfQui\u00e9n era \u00d1e\u00f1e Hern\u00e1ndez?<\/h3>\n<p>Jos\u00e9 Guillermo Hern\u00e1ndez Aponte, conocido como \u00ab\u00d1e\u00f1e Hern\u00e1ndez,\u00bb fue un ganadero, empresario, y figura p\u00fablica colombiana. Naci\u00f3 en Valledupar el 9 de octubre de 1965 y fue asesinado en Brasil el 2 de mayo de 2019. Hern\u00e1ndez era conocido por su vida de alta sociedad y su matrimonio con la exreina de belleza Mar\u00eda M\u00f3nica Urbina.<\/p>\n<figure id=\"attachment_10880\" aria-describedby=\"caption-attachment-10880\" style=\"width: 1200px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2023\/07\/jose-guillermo-nene-hernandez-maria-monica-urbina6.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-10880\" src=\"https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2023\/07\/jose-guillermo-nene-hernandez-maria-monica-urbina6.jpg\" alt=\"\" width=\"1200\" height=\"1500\" srcset=\"https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2023\/07\/jose-guillermo-nene-hernandez-maria-monica-urbina6.jpg 1200w, https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2023\/07\/jose-guillermo-nene-hernandez-maria-monica-urbina6-240x300.jpg 240w, https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2023\/07\/jose-guillermo-nene-hernandez-maria-monica-urbina6-819x1024.jpg 819w, https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2023\/07\/jose-guillermo-nene-hernandez-maria-monica-urbina6-768x960.jpg 768w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><\/a><figcaption id=\"caption-attachment-10880\" class=\"wp-caption-text\">Jos\u00e9 Guillermo \u00ab\u00d1e\u00f1e\u00bb Hern\u00e1ndez y su esposa Mar\u00eda M\u00f3nica Urbina<\/figcaption><\/figure>\n<p>Hern\u00e1ndez hab\u00eda sido objeto de tres atentados fallidos contra su vida. Las autoridades colombianas lo investigaban por varios delitos, incluyendo un homicidio en 2011, del que se sospechaba su autor\u00eda intelectual. Las interceptaciones de sus conversaciones telef\u00f3nicas revelaron v\u00ednculos con el narcotr\u00e1fico y lavado de activos. Se cree que Hern\u00e1ndez estaba involucrado en la red de narcotr\u00e1fico de Marquitos Figueroa en Brasil, y que hab\u00eda delegado el manejo de esta red despu\u00e9s de la detenci\u00f3n de Figueroa en 2014.<\/p>\n<p>Hern\u00e1ndez tambi\u00e9n fue se\u00f1alado de financiar la campa\u00f1a presidencial de Iv\u00e1n Duque en 2018, lo que gener\u00f3 un gran esc\u00e1ndalo pol\u00edtico conocido en Colombia como la \u00ab\u00d1e\u00f1epol\u00edtica\u00bb. Sin embargo, se encontraron grabaciones telef\u00f3nicas que suger\u00edan la compra de votos para Duque en la regi\u00f3n de La Guajira y C\u00e9sar.<\/p>\n<figure id=\"attachment_10872\" aria-describedby=\"caption-attachment-10872\" style=\"width: 1200px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2023\/07\/maria-monica-urbina-ivan-duque-nene-hernandez.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-10872\" src=\"https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2023\/07\/maria-monica-urbina-ivan-duque-nene-hernandez.jpg\" alt=\"\" width=\"1200\" height=\"1199\" srcset=\"https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2023\/07\/maria-monica-urbina-ivan-duque-nene-hernandez.jpg 1200w, https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2023\/07\/maria-monica-urbina-ivan-duque-nene-hernandez-300x300.jpg 300w, https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2023\/07\/maria-monica-urbina-ivan-duque-nene-hernandez-1024x1024.jpg 1024w, https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2023\/07\/maria-monica-urbina-ivan-duque-nene-hernandez-150x150.jpg 150w, https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2023\/07\/maria-monica-urbina-ivan-duque-nene-hernandez-768x767.jpg 768w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><\/a><figcaption id=\"caption-attachment-10872\" class=\"wp-caption-text\">El expresidente colombiano Iv\u00e1n Duque (centro), al lado de Jos\u00e9 Guillermo \u00ab\u00d1e\u00f1e\u00bb Hern\u00e1ndez y Mar\u00eda M\u00f3nica Urbina, la esposa de Hern\u00e1ndez.<\/figcaption><\/figure>\n<p>En junio de 2019, las autoridades colombianas aplicaron extinci\u00f3n de dominio a sus propiedades, que inclu\u00edan fincas, estaciones de combustible, establecimientos comerciales, sociedades relacionadas con hidrocarburos, inmuebles, y veh\u00edculos, valorados en m\u00e1s de 2 billones de pesos colombianos.<\/p>\n<p>Jos\u00e9 Guillermo \u00ab\u00d1e\u00f1e\u00bb Hern\u00e1ndez era sospechoso de estar involucrado en el asesinato de \u00d3scar Eduardo Rodr\u00edguez Pomar, hijo del sastre Carlos Eduardo Rodr\u00edguez, seg\u00fan varias pruebas y testimonios. Deuda con Carlos Rodr\u00edguez: Hern\u00e1ndez ten\u00eda una deuda de 2.000 millones de pesos con Carlos Rodr\u00edguez, el padre de \u00d3scar Eduardo Rodr\u00edguez Pomar. Los sicarios de Marquitos Figueroa, condenados por el crimen, confesaron que Hern\u00e1ndez recolect\u00f3 200 millones de pesos para pagar por el asesinato de Carlos Rodr\u00edguez, pero en lugar de eso, mataron a su hijo \u00d3scar Eduardo por confusi\u00f3n. Los testimonios coincidieron en que el crimen se ejecut\u00f3 para saldar la deuda con Carlos Rodr\u00edguez.<\/p>\n<p>Rodr\u00edguez Pomar era un joven de 29 a\u00f1os que fue asesinado el 18 de agosto de 2011 en el norte de Barranquilla. Su padre, Carlos Eduardo Rodr\u00edguez, era un sastre y prestamista con quien \u00ab\u00d1e\u00f1e\u00bb Hern\u00e1ndez ten\u00eda una deuda pendiente.<\/p>\n<figure id=\"attachment_10853\" aria-describedby=\"caption-attachment-10853\" style=\"width: 1200px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2023\/07\/Alvaro-Uribe-Alvaro-Uribe.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-10853\" src=\"https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2023\/07\/Alvaro-Uribe-Alvaro-Uribe.jpg\" alt=\"\" width=\"1200\" height=\"1200\" srcset=\"https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2023\/07\/Alvaro-Uribe-Alvaro-Uribe.jpg 1200w, https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2023\/07\/Alvaro-Uribe-Alvaro-Uribe-300x300.jpg 300w, https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2023\/07\/Alvaro-Uribe-Alvaro-Uribe-1024x1024.jpg 1024w, https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2023\/07\/Alvaro-Uribe-Alvaro-Uribe-150x150.jpg 150w, https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2023\/07\/Alvaro-Uribe-Alvaro-Uribe-768x768.jpg 768w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><\/a><figcaption id=\"caption-attachment-10853\" class=\"wp-caption-text\">\u00c1lvaro Uribe y Jos\u00e9 Gullermo \u00ab\u00d1e\u00f1e\u00bb Hern\u00e1ndez (en el centro de la foto)<\/figcaption><\/figure>\n<p>\u00ab\u00d1e\u00f1e\u00bb Hern\u00e1ndez lleg\u00f3 a fotografiarse con varios pol\u00edticos y figuras p\u00fablicas en Colombia. Algunos de ellos fueron el expresidente \u00c1lvaro Uribe, el entonces presidente Iv\u00e1n Duque, Mar\u00eda Claudia Daza (asesora personal del expresidente \u00c1lvaro Uribe y quien apareci\u00f3 en conversaciones telef\u00f3nicas con \u00ab\u00d1e\u00f1e\u00bb Hern\u00e1ndez), Nubia Stella Mart\u00ednez (exdirectora del partido Centro Democr\u00e1tico), los generales Adolfo Hern\u00e1ndez y Ricardo Restrepo, entre otros.<\/p>\n<p>Las fotos y conversaciones telef\u00f3nicas reveladas generaron un gran esc\u00e1ndalo pol\u00edtico en Colombia, relacionado con la supuesta financiaci\u00f3n de la campa\u00f1a presidencial de Iv\u00e1n Duque con dinero del narcotr\u00e1fico.<\/p>\n<h3>Nexos ganaderos en Santander<\/h3>\n<p>Corr\u00eda el a\u00f1o 2016, cuando en medio del bullicio de una celebraci\u00f3n en los alrededores de Bucaramanga, se encontraron dos figuras del mundo ganadero del departamento de Santander: Jos\u00e9 Guillermo Hern\u00e1ndez Aponte, alias \u00ab\u00d1e\u00f1e\u00bb Hern\u00e1ndez, y Juan Felipe Pacheco P\u00e9rez. La m\u00fasica del reconocido cantante de vallenato Iv\u00e1n Villaz\u00f3n, animaba la velada donde ambos personajes, conocidos por su pasi\u00f3n por la cr\u00eda de Brahman rojo, se codeaban con la \u00e9lite ganadera. Este encuentro, aparentemente casual, es solo una pieza m\u00e1s en un complejo entramado de relaciones que une a Pacheco P\u00e9rez con una trama que trasciende los l\u00edmites de la ganader\u00eda.<\/p>\n<figure id=\"attachment_10826\" aria-describedby=\"caption-attachment-10826\" style=\"width: 1200px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2023\/07\/Ivan-Villazon-Juan-Felipe-Pacheco.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-10826\" src=\"https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2023\/07\/Ivan-Villazon-Juan-Felipe-Pacheco.jpg\" alt=\"\" width=\"1200\" height=\"1200\" srcset=\"https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2023\/07\/Ivan-Villazon-Juan-Felipe-Pacheco.jpg 1200w, https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2023\/07\/Ivan-Villazon-Juan-Felipe-Pacheco-300x300.jpg 300w, https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2023\/07\/Ivan-Villazon-Juan-Felipe-Pacheco-1024x1024.jpg 1024w, https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2023\/07\/Ivan-Villazon-Juan-Felipe-Pacheco-150x150.jpg 150w, https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2023\/07\/Ivan-Villazon-Juan-Felipe-Pacheco-768x768.jpg 768w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><\/a><figcaption id=\"caption-attachment-10826\" class=\"wp-caption-text\">Iv\u00e1n Villaz\u00f3n (camisa azul a rayas) y Juan Felipe Pacheco (camisa blanca) durante fiesta, en noviembre de 2016<\/figcaption><\/figure>\n<p>El v\u00ednculo entre \u00ab\u00d1e\u00f1e\u00bb Hern\u00e1ndez y Pacheco P\u00e9rez no se limitaba a un simple inter\u00e9s com\u00fan por el ganado. La muerte de Hern\u00e1ndez, acaecida el 2 de mayo de 2019, desat\u00f3 una ola de condolencias en redes sociales, entre las que destacaba un sentido mensaje de Pacheco P\u00e9rez. Las palabras de Pacheco, acompa\u00f1adas de una fotograf\u00eda donde ambos personajes compart\u00edan sonrisas en un encuentro pasado, reflejaban una cercan\u00eda que iba m\u00e1s all\u00e1 de la simple cortes\u00eda.<\/p>\n<figure id=\"attachment_10820\" aria-describedby=\"caption-attachment-10820\" style=\"width: 1200px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2023\/07\/nene-hernandez-juan-felipe-pacheco.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-10820\" src=\"https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2023\/07\/nene-hernandez-juan-felipe-pacheco.jpg\" alt=\"\" width=\"1200\" height=\"1187\" srcset=\"https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2023\/07\/nene-hernandez-juan-felipe-pacheco.jpg 1200w, https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2023\/07\/nene-hernandez-juan-felipe-pacheco-300x297.jpg 300w, https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2023\/07\/nene-hernandez-juan-felipe-pacheco-1024x1013.jpg 1024w, https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2023\/07\/nene-hernandez-juan-felipe-pacheco-768x760.jpg 768w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><\/a><figcaption id=\"caption-attachment-10820\" class=\"wp-caption-text\">Jos\u00e9 Guillermo \u00ab\u00d1e\u00f1e\u00bb Hern\u00e1ndez y Juan Felipe Pacheco P\u00e9rez.<\/figcaption><\/figure>\n<p>Un video de aquella fiesta de 2016 revelar\u00eda la camarader\u00eda que exist\u00eda entre ambos hombres. En la grabaci\u00f3n, se pod\u00eda apreciar a Hern\u00e1ndez, en un gesto de evidente confianza, acariciando el cabello y sosteniendo su mano sobre la cabeza de Pacheco mientras le dirig\u00eda unas palabras que se perd\u00edan entre la m\u00fasica de Villaz\u00f3n. La escena, impregnada de risas y euforia, mostraba a ambos ganaderos en un estado de visible embriaguez. En un momento de la celebraci\u00f3n, Pacheco llam\u00f3 al propio Villaz\u00f3n para inmortalizar el encuentro con una fotograf\u00eda, la cual se convertir\u00eda en un testimonio gr\u00e1fico de la relaci\u00f3n que ambos hombres hab\u00edan forjado.<\/p>\n<div style=\"left: 0; width: 100%; height: 0; position: relative; padding-bottom: 56.0081%;\"><iframe style=\"top: 0; left: 0; width: 100%; height: 100%; position: absolute; border: 0;\" src=\"https:\/\/ok.ru\/videoembed\/7120115534337\" scrolling=\"no\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/div>\n<p>&nbsp;<\/p>\n<p>La congoja de Pacheco P\u00e9rez por la muerte de su \u00abvecino\u00bb, como \u00e9l mismo se refer\u00eda a Hern\u00e1ndez, no fue un sentimiento aislado. En sus mensajes de condolencias, Pacheco dejaba entrever que la tristeza embargaba tambi\u00e9n a otro personaje cercano a Hern\u00e1ndez: Vicente Rujano Gar\u00f3falo. Este detalle cobraba relevancia al destaparse la estrecha relaci\u00f3n que ha unido a Rujano con el mundo de la ganader\u00eda y, en particular, con \u00ab\u00d1e\u00f1e\u00bb Hern\u00e1ndez.<\/p>\n<figure id=\"attachment_10835\" aria-describedby=\"caption-attachment-10835\" style=\"width: 1200px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2023\/07\/nene-hernandez-juan-felipe-pacheco001.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-10835\" src=\"https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2023\/07\/nene-hernandez-juan-felipe-pacheco001.jpg\" alt=\"\" width=\"1200\" height=\"671\" srcset=\"https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2023\/07\/nene-hernandez-juan-felipe-pacheco001.jpg 1200w, https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2023\/07\/nene-hernandez-juan-felipe-pacheco001-300x168.jpg 300w, https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2023\/07\/nene-hernandez-juan-felipe-pacheco001-1024x573.jpg 1024w, https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2023\/07\/nene-hernandez-juan-felipe-pacheco001-768x429.jpg 768w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><\/a><figcaption id=\"caption-attachment-10835\" class=\"wp-caption-text\">Jos\u00e9 Guillermo \u00ab\u00d1e\u00f1e\u00bb Hern\u00e1ndez y Juan Felipe Pacheco P\u00e9rez en fiesta celebrada en 2016.<\/figcaption><\/figure>\n<h3>Lazos familiares y empresariales<\/h3>\n<p>La relaci\u00f3n entre Pacheco y Rujano no se limita a una simple amistad. Pacheco, reconocido criador de brahman rojo en su hacienda La Magdalena, ubicada en el municipio Sabana de Torres del departamento de Santander, funge como criador de ganado para Rujano. En el mismo departamento, entre los lugare\u00f1os, a ambos se les conoce como \u00absocios\u00bb.<\/p>\n<p>La amistad de Pacheco y Vicente Rujano se extiende tambi\u00e9n a otros personajes de renombre en el sector ganadero colombiano, como Juan Santiago Mart\u00ednez Molina, propietario de la finca El Caney, en Antioquia, reconocida por su enfoque en el mejoramiento gen\u00e9tico del ganado.<\/p>\n<figure id=\"attachment_10840\" aria-describedby=\"caption-attachment-10840\" style=\"width: 1200px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2023\/07\/Juan-Felipe-Pacheco-Juan-Santiago-Martinez-Vicente-Rujano002.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-10840\" src=\"https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2023\/07\/Juan-Felipe-Pacheco-Juan-Santiago-Martinez-Vicente-Rujano002.jpg\" alt=\"\" width=\"1200\" height=\"1496\" srcset=\"https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2023\/07\/Juan-Felipe-Pacheco-Juan-Santiago-Martinez-Vicente-Rujano002.jpg 1200w, https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2023\/07\/Juan-Felipe-Pacheco-Juan-Santiago-Martinez-Vicente-Rujano002-241x300.jpg 241w, https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2023\/07\/Juan-Felipe-Pacheco-Juan-Santiago-Martinez-Vicente-Rujano002-821x1024.jpg 821w, https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2023\/07\/Juan-Felipe-Pacheco-Juan-Santiago-Martinez-Vicente-Rujano002-768x957.jpg 768w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><\/a><figcaption id=\"caption-attachment-10840\" class=\"wp-caption-text\">Juan Felipe Pacheco (al frente) y detr\u00e1s de \u00e9l, Juan Santiago Mart\u00ednez y Vicente Rujano.<\/figcaption><\/figure>\n<p>Sin embargo, la sombra de \u00ab\u00d1e\u00f1e\u00bb Hern\u00e1ndez se extiende tambi\u00e9n sobre la familia de Vicente Rujano. Un a\u00f1o antes del tr\u00e1gico final de Hern\u00e1ndez, un evento empresarial sac\u00f3 a la luz, en agosto de 2018, la estrecha relaci\u00f3n entre ambas familias. Se trat\u00f3 de una campa\u00f1a publicitaria de Carnes Grin, una empresa colombiana dedicada a la comercializaci\u00f3n de carne procesada con sede en Bucaramanga. Lo que en principio parec\u00eda un evento m\u00e1s en el sector c\u00e1rnico colombiano, escond\u00eda un detalle revelador: Mar\u00eda M\u00f3nica Urbina, esposa de \u00ab\u00d1e\u00f1e\u00bb Hern\u00e1ndez, hac\u00eda acto de presencia para promocionar la marca, sosteniendo en su mano un empaque de Carnes Grin.<\/p>\n<figure id=\"attachment_10844\" aria-describedby=\"caption-attachment-10844\" style=\"width: 1200px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2023\/07\/carnes-grin.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-10844\" src=\"https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2023\/07\/carnes-grin.jpg\" alt=\"\" width=\"1200\" height=\"600\" srcset=\"https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2023\/07\/carnes-grin.jpg 1200w, https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2023\/07\/carnes-grin-300x150.jpg 300w, https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2023\/07\/carnes-grin-1024x512.jpg 1024w, https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2023\/07\/carnes-grin-768x384.jpg 768w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><\/a><figcaption id=\"caption-attachment-10844\" class=\"wp-caption-text\">Carnes Grin<\/figcaption><\/figure>\n<p>Acompa\u00f1ando a Urbina en esa promoci\u00f3n, se encontraba Juan Felipe Pacheco y, en un gesto que no pas\u00f3 desapercibido, Waldo Rujano, padre de Vicente Rujano. Este \u00faltimo, que cuatro meses antes hab\u00eda cumplido su libertad condicional en Estados Unidos por conducir bajo los efectos del alcohol, reaparec\u00eda p\u00fablicamente junto a la esposa de \u00ab\u00d1e\u00f1e\u00bb Hern\u00e1ndez, en una clara muestra de la cercan\u00eda existente entre ambos entornos.<\/p>\n<p>Las fotograf\u00edas de aquel evento no dejan lugar a dudas: La esposa de \u00ab\u00d1e\u00f1e\u00bb Hern\u00e1ndez, con una amplia sonrisa, posaba junto a Pacheco y Waldo Rujano, quien a su vez abrazaba a una joven no identificada.<\/p>\n<figure id=\"attachment_10846\" aria-describedby=\"caption-attachment-10846\" style=\"width: 1200px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2023\/07\/Waldo-Rujano-Maria-Monica-Urbina-Juan-Felipe-Pacheco00.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-10846\" src=\"https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2023\/07\/Waldo-Rujano-Maria-Monica-Urbina-Juan-Felipe-Pacheco00.jpg\" alt=\"\" width=\"1200\" height=\"1607\" srcset=\"https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2023\/07\/Waldo-Rujano-Maria-Monica-Urbina-Juan-Felipe-Pacheco00.jpg 1200w, https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2023\/07\/Waldo-Rujano-Maria-Monica-Urbina-Juan-Felipe-Pacheco00-224x300.jpg 224w, https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2023\/07\/Waldo-Rujano-Maria-Monica-Urbina-Juan-Felipe-Pacheco00-765x1024.jpg 765w, https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2023\/07\/Waldo-Rujano-Maria-Monica-Urbina-Juan-Felipe-Pacheco00-768x1028.jpg 768w, https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2023\/07\/Waldo-Rujano-Maria-Monica-Urbina-Juan-Felipe-Pacheco00-1147x1536.jpg 1147w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><\/a><figcaption id=\"caption-attachment-10846\" class=\"wp-caption-text\">Waldo Rujano (segundo de izquierda a derecha); la esposa de \u00ab\u00d1e\u00f1e\u00bb Hern\u00e1ndez, Mar\u00eda M\u00f3nica Urbina (cuarta de izquierda a derecha, sosteniendo un empaque de Carnes Grin en su mano) y Juan Felipe Pacheco (segundo de derecha izquierda)<\/figcaption><\/figure>\n<p>En otra instant\u00e1nea, Urbina y el padre de Vicente Rujano aparecen solos, sonrientes y rodeados de productos de Carnes Grin. La presencia de la esposa de \u00ab\u00d1e\u00f1e\u00bb Hern\u00e1ndez en la promoci\u00f3n de una marca vinculada a Waldo Rujano y su familia, abre un interrogante sobre la verdadera naturaleza de la relaci\u00f3n entre ambos grupos familiares.<\/p>\n<figure id=\"attachment_10848\" aria-describedby=\"caption-attachment-10848\" style=\"width: 1200px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2023\/07\/Waldo-Rujano-y-Maria-Monica-Urbina.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-10848\" src=\"https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2023\/07\/Waldo-Rujano-y-Maria-Monica-Urbina.jpg\" alt=\"\" width=\"1200\" height=\"1500\" srcset=\"https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2023\/07\/Waldo-Rujano-y-Maria-Monica-Urbina.jpg 1200w, https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2023\/07\/Waldo-Rujano-y-Maria-Monica-Urbina-240x300.jpg 240w, https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2023\/07\/Waldo-Rujano-y-Maria-Monica-Urbina-819x1024.jpg 819w, https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2023\/07\/Waldo-Rujano-y-Maria-Monica-Urbina-768x960.jpg 768w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><\/a><figcaption id=\"caption-attachment-10848\" class=\"wp-caption-text\">Waldo Rujano y Mar\u00eda M\u00f3nica Urbina, esposa de \u00ab\u00d1e\u00f1e\u00bb Hern\u00e1ndez<\/figcaption><\/figure>\n<figure id=\"attachment_10857\" aria-describedby=\"caption-attachment-10857\" style=\"width: 1200px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2023\/07\/maria-monica-uribina-nene-hernandez.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-10857\" src=\"https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2023\/07\/maria-monica-uribina-nene-hernandez.jpg\" alt=\"\" width=\"1200\" height=\"1500\" srcset=\"https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2023\/07\/maria-monica-uribina-nene-hernandez.jpg 1200w, https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2023\/07\/maria-monica-uribina-nene-hernandez-240x300.jpg 240w, https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2023\/07\/maria-monica-uribina-nene-hernandez-819x1024.jpg 819w, https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2023\/07\/maria-monica-uribina-nene-hernandez-768x960.jpg 768w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><\/a><figcaption id=\"caption-attachment-10857\" class=\"wp-caption-text\">Mar\u00eda M\u00f3nica Urbina y su esposo Jos\u00e9 Guillermo \u00ab\u00d1e\u00f1e\u00bb Hern\u00e1ndez<\/figcaption><\/figure>\n<p>Las sospechas sobre la relaci\u00f3n entre Carnes Grin y el c\u00edrculo de Rujano no son infundadas. Las representantes legales de Carnes Grin S.A.S., la sociedad que controla la marca, son: Tamaithi Ocampo Hevia, ciudadana colombovenezolana, y Diana Yurley Arenas Rueda, contadora colombiana, quienes mantienen una relaci\u00f3n de subalternidad para con los Rujano. Seg\u00fan lugare\u00f1os de Bucaramanga, ambas mujeres fungir\u00edan como testaferros de los Rujano Gar\u00f3falo.<\/p>\n<figure id=\"attachment_10842\" aria-describedby=\"caption-attachment-10842\" style=\"width: 1200px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2023\/07\/Tamaithi-Ocampo-Hevia-y-Diana-Yurley-Arenas.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-10842\" src=\"https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2023\/07\/Tamaithi-Ocampo-Hevia-y-Diana-Yurley-Arenas.jpg\" alt=\"\" width=\"1200\" height=\"600\" srcset=\"https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2023\/07\/Tamaithi-Ocampo-Hevia-y-Diana-Yurley-Arenas.jpg 1200w, https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2023\/07\/Tamaithi-Ocampo-Hevia-y-Diana-Yurley-Arenas-300x150.jpg 300w, https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2023\/07\/Tamaithi-Ocampo-Hevia-y-Diana-Yurley-Arenas-1024x512.jpg 1024w, https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2023\/07\/Tamaithi-Ocampo-Hevia-y-Diana-Yurley-Arenas-768x384.jpg 768w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><\/a><figcaption id=\"caption-attachment-10842\" class=\"wp-caption-text\">Tamaithi Ocampo Hevia y Diana Yurley Arenas<\/figcaption><\/figure>\n<p>La vinculaci\u00f3n empresarial entre Tamaithi Ocampo Hevia y la familia Rujano Gar\u00f3falo trasciende las fronteras colombianas. En Panam\u00e1, operan la sociedad Global Enterprise Wavg, Inc., una compa\u00f1\u00eda en la que Ocampo Hevia ocupa el cargo de directora. Lo llamativo de esta empresa es la composici\u00f3n de su junta directiva: Andrea Paola Rujano Gar\u00f3falo, hermana de Vicente Rujano, figura como presidenta, mientras que Gisela Coromoto Gar\u00f3falo de Rujano, madre de Vicente, ocupa el puesto de directora.<\/p>\n<h3>Un entramado empresarial con tent\u00e1culos internacionales<\/h3>\n<p>Las siglas \u00abWavg\u00bb en el nombre de la empresa paname\u00f1a, parecen esconder un gui\u00f1o familiar: las iniciales de Waldo, Andrea, Vicente y Gisela, miembros del clan Rujano Gar\u00f3falo. Global Enterprise Wavg, Inc. no es la \u00fanica sociedad que han compartido los Rujano y Ocampo Hevia en territorio paname\u00f1o. Anteriormente, ambos grupos hab\u00edan operado a trav\u00e9s de Track Industries, S.A., una compa\u00f1\u00eda donde figuraban como directivos Cesar Augusto Ocampo Hevia, hermano de Tamaithi y viejo amigo de Vicente, adem\u00e1s del propio Vicente Rujano Gar\u00f3falo.<\/p>\n<figure id=\"attachment_10859\" aria-describedby=\"caption-attachment-10859\" style=\"width: 1200px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2023\/07\/waldo-rujano-gisela-garofalo.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-10859\" src=\"https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2023\/07\/waldo-rujano-gisela-garofalo.jpg\" alt=\"\" width=\"1200\" height=\"600\" srcset=\"https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2023\/07\/waldo-rujano-gisela-garofalo.jpg 1200w, https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2023\/07\/waldo-rujano-gisela-garofalo-300x150.jpg 300w, https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2023\/07\/waldo-rujano-gisela-garofalo-1024x512.jpg 1024w, https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2023\/07\/waldo-rujano-gisela-garofalo-768x384.jpg 768w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><\/a><figcaption id=\"caption-attachment-10859\" class=\"wp-caption-text\">Waldo Rujano y su esposa Gisela Gar\u00f3falo de Rujano<\/figcaption><\/figure>\n<p>La presidencia de Track Industries, S.A. estaba en manos de Daniel Gerardo S\u00e1nchez Hevia, un ciudadano venezolano originario del estado T\u00e1chira, al igual que la familia Rujano. Este entramado de empresas, con ramificaciones en Colombia y Panam\u00e1, despiertan ahora serias dudas sobre el origen de los fondos y las actividades que se esconden tras la fachada empresarial.<\/p>\n<p>La inc\u00f3gnita sobre la relaci\u00f3n entre \u00ab\u00d1e\u00f1e\u00bb Hern\u00e1ndez, su esposa, y la familia Rujano Gar\u00f3falo permanece latente. La participaci\u00f3n de Mar\u00eda M\u00f3nica Urbina en la promoci\u00f3n de Carnes Grin, marca vinculada a los Rujano, y la presencia de Waldo Rujano junto a la esposa del narcoganadero, en dicho evento, evidencian un v\u00ednculo que parece ir m\u00e1s all\u00e1 de la simple cortes\u00eda. \u00bfQu\u00e9 tipo de negocios o intereses comunes han podido unir a un narcoganadero con un clan familiar venezolano envuelto en una red de empresas opacas?<\/p>\n<p>Las dudas persisten: \u00bfPor qu\u00e9 Mar\u00eda M\u00f3nica Urbina se prest\u00f3 para promocionar Carnes Grin, una marca vinculada a la familia Rujano Gar\u00f3falo, justo cuando el nombre de \u201c\u00d1e\u00f1e\u201d Hern\u00e1ndez comenzaba a sonar con fuerza en los c\u00edrculos judiciales? La respuesta, al menos p\u00fablicamente, sigue siendo un misterio. La extra\u00f1a coincidencia de las relaciones empresariales y familiares, y la opacidad de algunos negocios, generan m\u00e1s preguntas que respuestas.<\/p>\n<p>La pregunta sobre hasta qu\u00e9 punto la fortuna de los Rujano Gar\u00f3falo se benefici\u00f3 de su relaci\u00f3n con \u00ab\u00d1e\u00f1e\u00bb Hern\u00e1ndez, sigue sin respuesta. Sus negocios, que se extienden desde Colombia hasta Estados Unidos, pasando por Venezuela y Panam\u00e1, plantean serias dudas sobre la legalidad de sus operaciones. La sombra de la sospecha se cierne sobre el imperio empresarial de los Rujano, mientras que la figura de \u00ab\u00d1e\u00f1e\u00bb Hern\u00e1ndez sigue presente, como un fantasma que recuerda los oscuros v\u00ednculos que se tejen en el mundo empresarial y ganadero colombiano.<\/p>\n<figure id=\"attachment_10861\" aria-describedby=\"caption-attachment-10861\" style=\"width: 1200px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2023\/07\/juan-felipe-pacheco-vicente-rujano003.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-10861\" src=\"https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2023\/07\/juan-felipe-pacheco-vicente-rujano003.jpg\" alt=\"\" width=\"1200\" height=\"864\" srcset=\"https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2023\/07\/juan-felipe-pacheco-vicente-rujano003.jpg 1200w, https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2023\/07\/juan-felipe-pacheco-vicente-rujano003-300x216.jpg 300w, https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2023\/07\/juan-felipe-pacheco-vicente-rujano003-1024x737.jpg 1024w, https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2023\/07\/juan-felipe-pacheco-vicente-rujano003-768x553.jpg 768w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><\/a><figcaption id=\"caption-attachment-10861\" class=\"wp-caption-text\">Juan Felipe Pacheco y Vicente Rujano (primero y segundo a la izquierda de la foto, respectivamente)<\/figcaption><\/figure>\n<p>Mientras tanto, Juan Felipe Pacheco, el amigo y \u00abvecino\u00bb de \u00ab\u00d1e\u00f1e\u00bb Hern\u00e1ndez, contin\u00faa tambi\u00e9n con sus actividades ganaderas en su Hacienda La Magdalena. Miembro activo de la Asociaci\u00f3n Colombiana de Criadores de Ganado Ceb\u00fa (Asoceb\u00fa), Pacheco participa en expoferias, exhibiciones, competencias y otros eventos ganaderos en Colombia, Venezuela, Estados Unidos &#8211; en Texas &#8211; e incluso Emiratos \u00c1rabes Unidos, siempre buscando expandir sus horizontes empresariales.<\/p>\n<figure id=\"attachment_10851\" aria-describedby=\"caption-attachment-10851\" style=\"width: 1200px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2023\/07\/Juan-Felipe-Pacheco-Juan-Santiago-Martinez.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-10851\" src=\"https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2023\/07\/Juan-Felipe-Pacheco-Juan-Santiago-Martinez.jpg\" alt=\"\" width=\"1200\" height=\"803\" srcset=\"https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2023\/07\/Juan-Felipe-Pacheco-Juan-Santiago-Martinez.jpg 1200w, https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2023\/07\/Juan-Felipe-Pacheco-Juan-Santiago-Martinez-300x201.jpg 300w, https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2023\/07\/Juan-Felipe-Pacheco-Juan-Santiago-Martinez-1024x685.jpg 1024w, https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2023\/07\/Juan-Felipe-Pacheco-Juan-Santiago-Martinez-768x514.jpg 768w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><\/a><figcaption id=\"caption-attachment-10851\" class=\"wp-caption-text\">En el centro de la foto, Juan Santiago Mart\u00ednez y Juan Felipe Pacheco sostienen premio durante la XLVII edici\u00f3n de la Feria Nacional del Ceb\u00fa y sus cruces, auspiciada por la Asociaci\u00f3n Venezolana de Criadores de Ganado (Asoceb\u00fa), realizada en abril de 2024 en el Parque Sim\u00f3n Bol\u00edvar, en La Carlota, Caracas &#8211; Venezuela.<\/figcaption><\/figure>\n<p>A pesar de su aparente \u00e9xito en el mundo ganadero, Pacheco ha arrastrado en a\u00f1os recientes un historial de deudas y demandas interpuestas por entidades bancarias como el Banco Ita\u00fa Colombia, Banco Davivienda y Scotiabank Colpatria, adem\u00e1s de varios litigios con particulares. Estos problemas financieros han llevado al embargo de algunos de sus activos, lo que contrasta con su imagen de pr\u00f3spero empresario ganadero. La figura de Pacheco, al igual que la de los dem\u00e1s personajes de esta historia, se mueve en una delgada l\u00ednea entre el \u00e9xito empresarial y la sombra de la sospecha.<\/p>\n<p>Las demandas interpuestas contra Pacheco por entidades financieras plantean tambi\u00e9n interrogantes sobre la salud financiera de sus negocios. \u00bfEst\u00e1n estas deudas relacionadas con sus actividades ganaderas o responden a otros intereses ocultos tras la fachada de Agropecuaria La Magdalena AGB y sus dem\u00e1s compa\u00f1\u00edas?<\/p>\n<p>Los Rujano Gar\u00f3falo parecen haber tejido una red empresarial opaca que se extiende desde Venezuela hasta Estados Unidos, pasando por Colombia. Si bien no existen pruebas concluyentes que los vinculen directamente con actividades il\u00edcitas, la sombra de la sospecha se cierne sobre el origen de su fortuna. Las autoridades deber\u00e1n investigar a fondo si detr\u00e1s de este imperio empresarial se esconde una compleja trama de lavado de dinero proveniente del narcotr\u00e1fico o de il\u00edcitos cambiarios.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En el turbulento mundo de los negocios, las fortunas opacas y los v\u00ednculos con el narcotr\u00e1fico, en ocasiones, van de la mano. Un caso que despierta interrogantes y alimenta rumores es el de la familia Rujano Gar\u00f3falo, originaria del estado T\u00e1chira en Venezuela. Si bien gozan de una posici\u00f3n econ\u00f3mica privilegiada, con empresas e inversiones [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":10892,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"h5ap_radio_sources":[],"footnotes":""},"categories":[1,23,9],"tags":[],"class_list":["post-10817","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ciudadgotica","category-estados-unidos","category-venezuela"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"En el turbulento mundo de los negocios, las fortunas opacas y los v\u00ednculos con el narcotr\u00e1fico, en ocasiones, van de la mano. Un caso que despierta interrogantes y alimenta rumores es el de la familia Rujano Gar\u00f3falo, originaria del estado T\u00e1chira en Venezuela. Si bien gozan de una posici\u00f3n econ\u00f3mica privilegiada, con empresas e inversiones\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"admin\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.ciudadgoticanews.com\/index.php\/2024\/07\/30\/escandalo-colombia-nene-hernandez-vicente-rujano\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"CIUDAD G\u00d3TICA NEWS - REVELANDO VERDADES OCULTAS\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"\u00a1Esc\u00e1ndalo! La sombra narcoganadera de \u00ab\u00d1e\u00f1e\u00bb Hern\u00e1ndez se cierne sobre los negocios del venezolano Vicente Rujano Gar\u00f3falo en Colombia, Venezuela y Estados Unidos - CIUDAD G\u00d3TICA NEWS\" \/>\n\t\t<meta property=\"og:description\" content=\"En el turbulento mundo de los negocios, las fortunas opacas y los v\u00ednculos con el narcotr\u00e1fico, en ocasiones, van de la mano. Un caso que despierta interrogantes y alimenta rumores es el de la familia Rujano Gar\u00f3falo, originaria del estado T\u00e1chira en Venezuela. Si bien gozan de una posici\u00f3n econ\u00f3mica privilegiada, con empresas e inversiones\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.ciudadgoticanews.com\/index.php\/2024\/07\/30\/escandalo-colombia-nene-hernandez-vicente-rujano\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2024-07-30T04:34:44+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2024-08-03T09:40:57+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"\u00a1Esc\u00e1ndalo! La sombra narcoganadera de \u00ab\u00d1e\u00f1e\u00bb Hern\u00e1ndez se cierne sobre los negocios del venezolano Vicente Rujano Gar\u00f3falo en Colombia, Venezuela y Estados Unidos - CIUDAD G\u00d3TICA NEWS\" \/>\n\t\t<meta name=\"twitter:description\" content=\"En el turbulento mundo de los negocios, las fortunas opacas y los v\u00ednculos con el narcotr\u00e1fico, en ocasiones, van de la mano. Un caso que despierta interrogantes y alimenta rumores es el de la familia Rujano Gar\u00f3falo, originaria del estado T\u00e1chira en Venezuela. Si bien gozan de una posici\u00f3n econ\u00f3mica privilegiada, con empresas e inversiones\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.ciudadgoticanews.com\\\/index.php\\\/2024\\\/07\\\/30\\\/escandalo-colombia-nene-hernandez-vicente-rujano\\\/#blogposting\",\"name\":\"\\u00a1Esc\\u00e1ndalo! La sombra narcoganadera de \\u00ab\\u00d1e\\u00f1e\\u00bb Hern\\u00e1ndez se cierne sobre los negocios del venezolano Vicente Rujano Gar\\u00f3falo en Colombia, Venezuela y Estados Unidos - CIUDAD G\\u00d3TICA NEWS\",\"headline\":\"\\u00a1Esc\\u00e1ndalo! La sombra narcoganadera de \\u00ab\\u00d1e\\u00f1e\\u00bb Hern\\u00e1ndez se cierne sobre los negocios del venezolano Vicente Rujano Gar\\u00f3falo en Colombia, Venezuela y Estados Unidos\",\"author\":{\"@id\":\"https:\\\/\\\/www.ciudadgoticanews.com\\\/index.php\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.ciudadgoticanews.com\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.ciudadgoticanews.com\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/rujano.jpg\",\"width\":1200,\"height\":600},\"datePublished\":\"2024-07-30T00:34:44-04:00\",\"dateModified\":\"2024-08-03T05:40:57-04:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.ciudadgoticanews.com\\\/index.php\\\/2024\\\/07\\\/30\\\/escandalo-colombia-nene-hernandez-vicente-rujano\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ciudadgoticanews.com\\\/index.php\\\/2024\\\/07\\\/30\\\/escandalo-colombia-nene-hernandez-vicente-rujano\\\/#webpage\"},\"articleSection\":\"Ciudad G\\u00f3tica, Estados Unidos, Venezuela\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ciudadgoticanews.com\\\/index.php\\\/2024\\\/07\\\/30\\\/escandalo-colombia-nene-hernandez-vicente-rujano\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.ciudadgoticanews.com#listItem\",\"position\":1,\"name\":\"Hogar\",\"item\":\"https:\\\/\\\/www.ciudadgoticanews.com\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.ciudadgoticanews.com\\\/index.php\\\/category\\\/ciudadgotica\\\/#listItem\",\"name\":\"Ciudad G\\u00f3tica\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.ciudadgoticanews.com\\\/index.php\\\/category\\\/ciudadgotica\\\/#listItem\",\"position\":2,\"name\":\"Ciudad G\\u00f3tica\",\"item\":\"https:\\\/\\\/www.ciudadgoticanews.com\\\/index.php\\\/category\\\/ciudadgotica\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.ciudadgoticanews.com\\\/index.php\\\/2024\\\/07\\\/30\\\/escandalo-colombia-nene-hernandez-vicente-rujano\\\/#listItem\",\"name\":\"\\u00a1Esc\\u00e1ndalo! La sombra narcoganadera de \\u00ab\\u00d1e\\u00f1e\\u00bb Hern\\u00e1ndez se cierne sobre los negocios del venezolano Vicente Rujano Gar\\u00f3falo en Colombia, Venezuela y Estados Unidos\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.ciudadgoticanews.com#listItem\",\"name\":\"Hogar\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.ciudadgoticanews.com\\\/index.php\\\/2024\\\/07\\\/30\\\/escandalo-colombia-nene-hernandez-vicente-rujano\\\/#listItem\",\"position\":3,\"name\":\"\\u00a1Esc\\u00e1ndalo! La sombra narcoganadera de \\u00ab\\u00d1e\\u00f1e\\u00bb Hern\\u00e1ndez se cierne sobre los negocios del venezolano Vicente Rujano Gar\\u00f3falo en Colombia, Venezuela y Estados Unidos\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.ciudadgoticanews.com\\\/index.php\\\/category\\\/ciudadgotica\\\/#listItem\",\"name\":\"Ciudad G\\u00f3tica\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.ciudadgoticanews.com\\\/#organization\",\"name\":\"CIUDAD G\\u00d3TICA NEWS\",\"description\":\"REVELANDO VERDADES OCULTAS\",\"url\":\"https:\\\/\\\/www.ciudadgoticanews.com\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.ciudadgoticanews.com\\\/index.php\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/www.ciudadgoticanews.com\\\/index.php\\\/author\\\/admin\\\/\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.ciudadgoticanews.com\\\/index.php\\\/2024\\\/07\\\/30\\\/escandalo-colombia-nene-hernandez-vicente-rujano\\\/#authorImage\",\"url\":\"https:\\\/\\\/www.ciudadgoticanews.com\\\/wp-content\\\/litespeed\\\/avatar\\\/7bdebc28a5ef0db3574308c1e2a6f08a.jpg?ver=1787761068\",\"width\":96,\"height\":96,\"caption\":\"admin\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ciudadgoticanews.com\\\/index.php\\\/2024\\\/07\\\/30\\\/escandalo-colombia-nene-hernandez-vicente-rujano\\\/#webpage\",\"url\":\"https:\\\/\\\/www.ciudadgoticanews.com\\\/index.php\\\/2024\\\/07\\\/30\\\/escandalo-colombia-nene-hernandez-vicente-rujano\\\/\",\"name\":\"\\u00a1Esc\\u00e1ndalo! La sombra narcoganadera de \\u00ab\\u00d1e\\u00f1e\\u00bb Hern\\u00e1ndez se cierne sobre los negocios del venezolano Vicente Rujano Gar\\u00f3falo en Colombia, Venezuela y Estados Unidos - CIUDAD G\\u00d3TICA NEWS\",\"description\":\"En el turbulento mundo de los negocios, las fortunas opacas y los v\\u00ednculos con el narcotr\\u00e1fico, en ocasiones, van de la mano. Un caso que despierta interrogantes y alimenta rumores es el de la familia Rujano Gar\\u00f3falo, originaria del estado T\\u00e1chira en Venezuela. Si bien gozan de una posici\\u00f3n econ\\u00f3mica privilegiada, con empresas e inversiones\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ciudadgoticanews.com\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ciudadgoticanews.com\\\/index.php\\\/2024\\\/07\\\/30\\\/escandalo-colombia-nene-hernandez-vicente-rujano\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.ciudadgoticanews.com\\\/index.php\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.ciudadgoticanews.com\\\/index.php\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.ciudadgoticanews.com\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/rujano.jpg\",\"@id\":\"https:\\\/\\\/www.ciudadgoticanews.com\\\/index.php\\\/2024\\\/07\\\/30\\\/escandalo-colombia-nene-hernandez-vicente-rujano\\\/#mainImage\",\"width\":1200,\"height\":600},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.ciudadgoticanews.com\\\/index.php\\\/2024\\\/07\\\/30\\\/escandalo-colombia-nene-hernandez-vicente-rujano\\\/#mainImage\"},\"datePublished\":\"2024-07-30T00:34:44-04:00\",\"dateModified\":\"2024-08-03T05:40:57-04:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ciudadgoticanews.com\\\/#website\",\"url\":\"https:\\\/\\\/www.ciudadgoticanews.com\\\/\",\"name\":\"CIUDAD G\\u00d3TICA NEWS\",\"description\":\"REVELANDO VERDADES OCULTAS\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.ciudadgoticanews.com\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"\u00a1Esc\u00e1ndalo! La sombra narcoganadera de \u00ab\u00d1e\u00f1e\u00bb Hern\u00e1ndez se cierne sobre los negocios del venezolano Vicente Rujano Gar\u00f3falo en Colombia, Venezuela y Estados Unidos - CIUDAD G\u00d3TICA NEWS","description":"En el turbulento mundo de los negocios, las fortunas opacas y los v\u00ednculos con el narcotr\u00e1fico, en ocasiones, van de la mano. Un caso que despierta interrogantes y alimenta rumores es el de la familia Rujano Gar\u00f3falo, originaria del estado T\u00e1chira en Venezuela. Si bien gozan de una posici\u00f3n econ\u00f3mica privilegiada, con empresas e inversiones","canonical_url":"https:\/\/www.ciudadgoticanews.com\/index.php\/2024\/07\/30\/escandalo-colombia-nene-hernandez-vicente-rujano\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.ciudadgoticanews.com\/index.php\/2024\/07\/30\/escandalo-colombia-nene-hernandez-vicente-rujano\/#blogposting","name":"\u00a1Esc\u00e1ndalo! La sombra narcoganadera de \u00ab\u00d1e\u00f1e\u00bb Hern\u00e1ndez se cierne sobre los negocios del venezolano Vicente Rujano Gar\u00f3falo en Colombia, Venezuela y Estados Unidos - CIUDAD G\u00d3TICA NEWS","headline":"\u00a1Esc\u00e1ndalo! La sombra narcoganadera de \u00ab\u00d1e\u00f1e\u00bb Hern\u00e1ndez se cierne sobre los negocios del venezolano Vicente Rujano Gar\u00f3falo en Colombia, Venezuela y Estados Unidos","author":{"@id":"https:\/\/www.ciudadgoticanews.com\/index.php\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/www.ciudadgoticanews.com\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2023\/07\/rujano.jpg","width":1200,"height":600},"datePublished":"2024-07-30T00:34:44-04:00","dateModified":"2024-08-03T05:40:57-04:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/www.ciudadgoticanews.com\/index.php\/2024\/07\/30\/escandalo-colombia-nene-hernandez-vicente-rujano\/#webpage"},"isPartOf":{"@id":"https:\/\/www.ciudadgoticanews.com\/index.php\/2024\/07\/30\/escandalo-colombia-nene-hernandez-vicente-rujano\/#webpage"},"articleSection":"Ciudad G\u00f3tica, Estados Unidos, Venezuela"},{"@type":"BreadcrumbList","@id":"https:\/\/www.ciudadgoticanews.com\/index.php\/2024\/07\/30\/escandalo-colombia-nene-hernandez-vicente-rujano\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.ciudadgoticanews.com#listItem","position":1,"name":"Hogar","item":"https:\/\/www.ciudadgoticanews.com","nextItem":{"@type":"ListItem","@id":"https:\/\/www.ciudadgoticanews.com\/index.php\/category\/ciudadgotica\/#listItem","name":"Ciudad G\u00f3tica"}},{"@type":"ListItem","@id":"https:\/\/www.ciudadgoticanews.com\/index.php\/category\/ciudadgotica\/#listItem","position":2,"name":"Ciudad G\u00f3tica","item":"https:\/\/www.ciudadgoticanews.com\/index.php\/category\/ciudadgotica\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.ciudadgoticanews.com\/index.php\/2024\/07\/30\/escandalo-colombia-nene-hernandez-vicente-rujano\/#listItem","name":"\u00a1Esc\u00e1ndalo! La sombra narcoganadera de \u00ab\u00d1e\u00f1e\u00bb Hern\u00e1ndez se cierne sobre los negocios del venezolano Vicente Rujano Gar\u00f3falo en Colombia, Venezuela y Estados Unidos"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.ciudadgoticanews.com#listItem","name":"Hogar"}},{"@type":"ListItem","@id":"https:\/\/www.ciudadgoticanews.com\/index.php\/2024\/07\/30\/escandalo-colombia-nene-hernandez-vicente-rujano\/#listItem","position":3,"name":"\u00a1Esc\u00e1ndalo! La sombra narcoganadera de \u00ab\u00d1e\u00f1e\u00bb Hern\u00e1ndez se cierne sobre los negocios del venezolano Vicente Rujano Gar\u00f3falo en Colombia, Venezuela y Estados Unidos","previousItem":{"@type":"ListItem","@id":"https:\/\/www.ciudadgoticanews.com\/index.php\/category\/ciudadgotica\/#listItem","name":"Ciudad G\u00f3tica"}}]},{"@type":"Organization","@id":"https:\/\/www.ciudadgoticanews.com\/#organization","name":"CIUDAD G\u00d3TICA NEWS","description":"REVELANDO VERDADES OCULTAS","url":"https:\/\/www.ciudadgoticanews.com\/"},{"@type":"Person","@id":"https:\/\/www.ciudadgoticanews.com\/index.php\/author\/admin\/#author","url":"https:\/\/www.ciudadgoticanews.com\/index.php\/author\/admin\/","name":"admin","image":{"@type":"ImageObject","@id":"https:\/\/www.ciudadgoticanews.com\/index.php\/2024\/07\/30\/escandalo-colombia-nene-hernandez-vicente-rujano\/#authorImage","url":"https:\/\/www.ciudadgoticanews.com\/wp-content\/litespeed\/avatar\/7bdebc28a5ef0db3574308c1e2a6f08a.jpg?ver=1787761068","width":96,"height":96,"caption":"admin"}},{"@type":"WebPage","@id":"https:\/\/www.ciudadgoticanews.com\/index.php\/2024\/07\/30\/escandalo-colombia-nene-hernandez-vicente-rujano\/#webpage","url":"https:\/\/www.ciudadgoticanews.com\/index.php\/2024\/07\/30\/escandalo-colombia-nene-hernandez-vicente-rujano\/","name":"\u00a1Esc\u00e1ndalo! La sombra narcoganadera de \u00ab\u00d1e\u00f1e\u00bb Hern\u00e1ndez se cierne sobre los negocios del venezolano Vicente Rujano Gar\u00f3falo en Colombia, Venezuela y Estados Unidos - CIUDAD G\u00d3TICA NEWS","description":"En el turbulento mundo de los negocios, las fortunas opacas y los v\u00ednculos con el narcotr\u00e1fico, en ocasiones, van de la mano. Un caso que despierta interrogantes y alimenta rumores es el de la familia Rujano Gar\u00f3falo, originaria del estado T\u00e1chira en Venezuela. Si bien gozan de una posici\u00f3n econ\u00f3mica privilegiada, con empresas e inversiones","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.ciudadgoticanews.com\/#website"},"breadcrumb":{"@id":"https:\/\/www.ciudadgoticanews.com\/index.php\/2024\/07\/30\/escandalo-colombia-nene-hernandez-vicente-rujano\/#breadcrumblist"},"author":{"@id":"https:\/\/www.ciudadgoticanews.com\/index.php\/author\/admin\/#author"},"creator":{"@id":"https:\/\/www.ciudadgoticanews.com\/index.php\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2023\/07\/rujano.jpg","@id":"https:\/\/www.ciudadgoticanews.com\/index.php\/2024\/07\/30\/escandalo-colombia-nene-hernandez-vicente-rujano\/#mainImage","width":1200,"height":600},"primaryImageOfPage":{"@id":"https:\/\/www.ciudadgoticanews.com\/index.php\/2024\/07\/30\/escandalo-colombia-nene-hernandez-vicente-rujano\/#mainImage"},"datePublished":"2024-07-30T00:34:44-04:00","dateModified":"2024-08-03T05:40:57-04:00"},{"@type":"WebSite","@id":"https:\/\/www.ciudadgoticanews.com\/#website","url":"https:\/\/www.ciudadgoticanews.com\/","name":"CIUDAD G\u00d3TICA NEWS","description":"REVELANDO VERDADES OCULTAS","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.ciudadgoticanews.com\/#organization"}}]},"og:locale":"es_ES","og:site_name":"CIUDAD G\u00d3TICA NEWS - REVELANDO VERDADES OCULTAS","og:type":"article","og:title":"\u00a1Esc\u00e1ndalo! La sombra narcoganadera de \u00ab\u00d1e\u00f1e\u00bb Hern\u00e1ndez se cierne sobre los negocios del venezolano Vicente Rujano Gar\u00f3falo en Colombia, Venezuela y Estados Unidos - CIUDAD G\u00d3TICA NEWS","og:description":"En el turbulento mundo de los negocios, las fortunas opacas y los v\u00ednculos con el narcotr\u00e1fico, en ocasiones, van de la mano. Un caso que despierta interrogantes y alimenta rumores es el de la familia Rujano Gar\u00f3falo, originaria del estado T\u00e1chira en Venezuela. Si bien gozan de una posici\u00f3n econ\u00f3mica privilegiada, con empresas e inversiones","og:url":"https:\/\/www.ciudadgoticanews.com\/index.php\/2024\/07\/30\/escandalo-colombia-nene-hernandez-vicente-rujano\/","article:published_time":"2024-07-30T04:34:44+00:00","article:modified_time":"2024-08-03T09:40:57+00:00","twitter:card":"summary_large_image","twitter:title":"\u00a1Esc\u00e1ndalo! La sombra narcoganadera de \u00ab\u00d1e\u00f1e\u00bb Hern\u00e1ndez se cierne sobre los negocios del venezolano Vicente Rujano Gar\u00f3falo en Colombia, Venezuela y Estados Unidos - CIUDAD G\u00d3TICA NEWS","twitter:description":"En el turbulento mundo de los negocios, las fortunas opacas y los v\u00ednculos con el narcotr\u00e1fico, en ocasiones, van de la mano. Un caso que despierta interrogantes y alimenta rumores es el de la familia Rujano Gar\u00f3falo, originaria del estado T\u00e1chira en Venezuela. Si bien gozan de una posici\u00f3n econ\u00f3mica privilegiada, con empresas e inversiones"},"aioseo_meta_data":{"post_id":"10817","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2024-10-17 12:38:53","updated":"2025-06-14 18:24:12","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.ciudadgoticanews.com\" title=\"Hogar\">Hogar<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.ciudadgoticanews.com\/index.php\/category\/ciudadgotica\/\" title=\"Ciudad G\u00f3tica\">Ciudad G\u00f3tica<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t\u00a1Esc\u00e1ndalo! La sombra narcoganadera de \u00ab\u00d1e\u00f1e\u00bb Hern\u00e1ndez se cierne sobre los negocios del venezolano Vicente Rujano Gar\u00f3falo en Colombia, Venezuela y Estados Unidos\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Hogar","link":"https:\/\/www.ciudadgoticanews.com"},{"label":"Ciudad G\u00f3tica","link":"https:\/\/www.ciudadgoticanews.com\/index.php\/category\/ciudadgotica\/"},{"label":"\u00a1Esc\u00e1ndalo! La sombra narcoganadera de \u00ab\u00d1e\u00f1e\u00bb Hern\u00e1ndez se cierne sobre los negocios del venezolano Vicente Rujano Gar\u00f3falo en Colombia, Venezuela y Estados Unidos","link":"https:\/\/www.ciudadgoticanews.com\/index.php\/2024\/07\/30\/escandalo-colombia-nene-hernandez-vicente-rujano\/"}],"_links":{"self":[{"href":"https:\/\/www.ciudadgoticanews.com\/index.php\/wp-json\/wp\/v2\/posts\/10817","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ciudadgoticanews.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ciudadgoticanews.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ciudadgoticanews.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ciudadgoticanews.com\/index.php\/wp-json\/wp\/v2\/comments?post=10817"}],"version-history":[{"count":0,"href":"https:\/\/www.ciudadgoticanews.com\/index.php\/wp-json\/wp\/v2\/posts\/10817\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ciudadgoticanews.com\/index.php\/wp-json\/wp\/v2\/media\/10892"}],"wp:attachment":[{"href":"https:\/\/www.ciudadgoticanews.com\/index.php\/wp-json\/wp\/v2\/media?parent=10817"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ciudadgoticanews.com\/index.php\/wp-json\/wp\/v2\/categories?post=10817"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ciudadgoticanews.com\/index.php\/wp-json\/wp\/v2\/tags?post=10817"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}