{"id":13221,"date":"2025-03-20T22:05:53","date_gmt":"2025-03-21T02:05:53","guid":{"rendered":"https:\/\/www.ciudadgoticanews.com\/?p=13221"},"modified":"2025-03-20T22:05:53","modified_gmt":"2025-03-21T02:05:53","slug":"escandalo-en-panama-juan-manuel-henriquez-exyerno-del-expresidente-laurentino-cortizo-y-el-precio-del-silencio-por-divorcio-de-carolina-cortizo","status":"publish","type":"post","link":"https:\/\/www.ciudadgoticanews.com\/index.php\/2025\/03\/20\/escandalo-en-panama-juan-manuel-henriquez-exyerno-del-expresidente-laurentino-cortizo-y-el-precio-del-silencio-por-divorcio-de-carolina-cortizo\/","title":{"rendered":"Esc\u00e1ndalo en Panam\u00e1: Juan Manuel Henr\u00edquez, exyerno del expresidente Laurentino Cortizo, y el precio del silencio por divorcio de Carolina Cortizo"},"content":{"rendered":"<p><em>(Fuente: <a href=\"https:\/\/reportedelaeconomia.com\/panama\/escandalo-panama-juan-manuel-henriquez-exyerno-expresidente-laurentino-cortizo-precio-silencio-divorcio-carolina-cortizo\/\">Reporte de la Economia<\/a>. Publicado el 20 de marzo de 2025) <\/em>La ruptura matrimonial entre Carolina Cortizo Col\u00f3n, hija del expresidente paname\u00f1o Laurentino Cortizo (quien gobern\u00f3 Panam\u00e1 desde el 1 de julio de 2019 hasta el 30 de junio de 2024), y Juan Manuel Henr\u00edquez Portuondo, acaecida hace m\u00e1s de tres a\u00f1os, antes del 14 de noviembre de 2024, fecha en la que se anunci\u00f3 el compromiso de Carolina con una mujer, desat\u00f3 una ola de rumores y especulaciones en Panam\u00e1. El matrimonio se hab\u00eda celebrado el 12 de julio de 2014. Si bien el foco medi\u00e1tico se centr\u00f3 en la posterior relaci\u00f3n sentimental de Carolina Cortizo y su anuncio de compromiso con otra mujer, una narrativa m\u00e1s oscura y menos comentada se tej\u00eda en los c\u00edrculos de poder: la del supuesto \u00abalivio\u00bb financiero otorgado a Henr\u00edquez durante la separaci\u00f3n.<\/p>\n<div id=\"post-body-92555\" class=\"post-body entry-content content-template wide-right\">\n<div class=\"post-body-inner\">\n<div id=\"attachment_92560\" class=\"wp-caption aligncenter\"><a class=\"thickbox\" title=\"Juan Manuel Henr\u00edquez y Carolina Cortizo\" href=\"https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2025\/03\/juan-manuel-henriquez-carolina-cortizo-2.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-92560\" src=\"https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2025\/03\/juan-manuel-henriquez-carolina-cortizo-2.jpg\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" srcset=\"https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2025\/03\/juan-manuel-henriquez-carolina-cortizo-2.jpg 1200w, https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2025\/03\/1_juan-manuel-henriquez-carolina-cortizo-2-300x207.jpg 300w, https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2025\/03\/1_juan-manuel-henriquez-carolina-cortizo-2-1024x707.jpg 1024w, https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2025\/03\/1_juan-manuel-henriquez-carolina-cortizo-2-768x531.jpg 768w, https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2025\/03\/juan-manuel-henriquez-carolina-cortizo-2-150x104.jpg 150w, https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2025\/03\/juan-manuel-henriquez-carolina-cortizo-2-650x449.jpg 650w, https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2025\/03\/juan-manuel-henriquez-carolina-cortizo-2-400x276.jpg 400w, https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2025\/03\/juan-manuel-henriquez-carolina-cortizo-2-250x173.jpg 250w\" alt=\"\" width=\"1200\" height=\"829\" aria-describedby=\"caption-attachment-92560\" \/><\/a><\/p>\n<p id=\"caption-attachment-92560\" class=\"wp-caption-text\">Juan Manuel Henr\u00edquez y Carolina Cortizo<\/p>\n<\/div>\n<p>Seg\u00fan fuentes, y como lo coment\u00f3 en redes sociales el perfil period\u00edstico \u00ab<a href=\"https:\/\/www.instagram.com\/p\/DHbOdqqgpV0\" target=\"_blank\" rel=\"noopener\">As\u00ed Est\u00e1n las Cosas<\/a>\u00ab, se especula que el silencio de Henr\u00edquez respecto a la vida personal de su exesposa, espec\u00edficamente en lo tocante a su orientaci\u00f3n sexual, habr\u00eda sido \u00abcomprado\u00bb con una serie de favores y prebendas. Una suerte de pacto no escrito, orquestado, presuntamente, desde las altas esferas del poder, durante el mandato de Laurentino Cortizo. El objetivo: evitar un esc\u00e1ndalo que pudiera empa\u00f1ar la imagen de la familia presidencial y, por extensi\u00f3n, la del propio mandatario.<\/p>\n<div id=\"repor-3407824048\" class=\"repor-contenido repor-highlight-wrapper\" data-title=\"Nombre de la ubicaci\u00f3n: Contenido; Anuncios: Donativos paciente renal\"><\/div>\n<div id=\"attachment_7735\" class=\"wp-caption aligncenter\"><a class=\"thickbox\" title=\"Laurentino Cortizo\" href=\"https:\/\/reportedelaeconomia.com\/wp-content\/uploads\/2022\/07\/malversacion-cortizo2-1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-7735\" src=\"https:\/\/reportedelaeconomia.com\/wp-content\/uploads\/2022\/07\/malversacion-cortizo2-1.jpg\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" srcset=\"https:\/\/reportedelaeconomia.com\/wp-content\/uploads\/2022\/07\/malversacion-cortizo2-1.jpg 700w, https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2025\/03\/malversacion-cortizo2-1-300x193.jpg 300w, https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2025\/03\/malversacion-cortizo2-1-200x129.jpg 200w\" alt=\"\" width=\"700\" height=\"450\" aria-describedby=\"caption-attachment-7735\" \/><\/a><\/p>\n<p id=\"caption-attachment-7735\" class=\"wp-caption-text\">Laurentino Cortizo<\/p>\n<\/div>\n<p>Algunos cr\u00edticos ven en esta situaci\u00f3n un claro indicio de c\u00f3mo el poder pol\u00edtico y econ\u00f3mico se entrelaza con los asuntos personales, utilizando los recursos del Estado como moneda de cambio para silenciar verdades inc\u00f3modas. La \u00abcompensaci\u00f3n\u00bb a Henr\u00edquez, un oscuro velo que se extiende sobre la transparencia que deber\u00eda caracterizar a un gobierno democr\u00e1tico.<\/p>\n<h3>Henr\u00edquez: De yerno presidencial a operador en la sombra<\/h3>\n<div id=\"attachment_92563\" class=\"wp-caption aligncenter\"><a class=\"thickbox\" title=\"Juan Manuel Henr\u00edquez\" href=\"https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2025\/03\/juan-manuel-henriquez-carolina-cortizo-3.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-92563\" src=\"https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2025\/03\/juan-manuel-henriquez-carolina-cortizo-3.jpg\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" srcset=\"https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2025\/03\/juan-manuel-henriquez-carolina-cortizo-3.jpg 1200w, https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2025\/03\/1_juan-manuel-henriquez-carolina-cortizo-3-300x213.jpg 300w, https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2025\/03\/1_juan-manuel-henriquez-carolina-cortizo-3-1024x725.jpg 1024w, https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2025\/03\/juan-manuel-henriquez-carolina-cortizo-3-768x544.jpg 768w, https:\/\/reportedelaeconomia.com\/wp-content\/uploads\/2025\/03\/juan-manuel-henriquez-carolina-cortizo-3-150x106.jpg 150w, https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2025\/03\/juan-manuel-henriquez-carolina-cortizo-3-650x460.jpg 650w, https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2025\/03\/juan-manuel-henriquez-carolina-cortizo-3-400x283.jpg 400w, https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2025\/03\/juan-manuel-henriquez-carolina-cortizo-3-250x177.jpg 250w\" alt=\"\" width=\"1200\" height=\"850\" aria-describedby=\"caption-attachment-92563\" \/><\/a><\/p>\n<p id=\"caption-attachment-92563\" class=\"wp-caption-text\">Juan Manuel Henr\u00edquez<\/p>\n<\/div>\n<p>La figura de Juan Manuel Henr\u00edquez, antes yerno del expresidente Laurentino Cortizo, se vislumbra en la directiva de la Hacienda Santa M\u00f3nica, propiedad de Alberto Vallarino. Este \u00faltimo, un empresario con fuertes intereses en el sector tur\u00edstico, es socio de los Eleta en el ambicioso proyecto Pearl Island, situado en la isla Pedro Gonz\u00e1lez. Esta conexi\u00f3n empresarial es clave para entender el supuesto rol de Henr\u00edquez como \u00abficha clave\u00bb, seg\u00fan un reportaje de la p\u00e1gina\u00a0Tierra de Resistentes, en la trama que benefici\u00f3 a los Eleta en el desarrollo de dicho enclave de lujo.<\/p>\n<p>Durante el gobierno de su entonces suegro, Laurentino Cortizo, Henr\u00edquez no se limit\u00f3 a ser un mero espectador. Se le atribuye haber promovido activamente el jugoso incentivo fiscal de 1.700 millones de d\u00f3lares destinado a los magnates del turismo, ese r\u00edo caudaloso de fondos p\u00fablicos que reg\u00f3 las arcas de empresarios como los Eleta y los Bern, socios de negocios de Alberto Vallarino. Este r\u00edo de millones, metaf\u00f3ricamente hablando, habr\u00eda servido para lubricar los engranajes de proyectos de lujo, mientras el pa\u00eds enfrentaba otras necesidades.<\/p>\n<p>Incluso, se asegura que Henr\u00edquez asisti\u00f3 a los debates de esta ley en la Asamblea Nacional durante 2019, operando tras bambalinas, cuid\u00e1ndose de no exponerse p\u00fablicamente. Una presencia discreta, pero influyente, moviendo los hilos desde la oscuridad para asegurar que el flujo de dinero beneficiara a sus asociados.<\/p>\n<h3>Viajes y vi\u00e1ticos: La sombra del exyerno en la comitiva presidencial<\/h3>\n<p><a class=\"thickbox\" href=\"https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2025\/03\/juan-manuel-henriquez-carolina-cortizo-4.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-92566\" src=\"https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2025\/03\/juan-manuel-henriquez-carolina-cortizo-4.jpg\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" srcset=\"https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2025\/03\/juan-manuel-henriquez-carolina-cortizo-4.jpg 1200w, https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2025\/03\/1_juan-manuel-henriquez-carolina-cortizo-4-300x213.jpg 300w, https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2025\/03\/1_juan-manuel-henriquez-carolina-cortizo-4-1024x725.jpg 1024w, https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2025\/03\/juan-manuel-henriquez-carolina-cortizo-4-768x544.jpg 768w, https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2025\/03\/juan-manuel-henriquez-carolina-cortizo-4-150x106.jpg 150w, https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2025\/03\/juan-manuel-henriquez-carolina-cortizo-4-650x460.jpg 650w, https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2025\/03\/juan-manuel-henriquez-carolina-cortizo-4-400x283.jpg 400w, https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2025\/03\/juan-manuel-henriquez-carolina-cortizo-4-250x177.jpg 250w\" alt=\"\" width=\"1200\" height=\"850\" \/><\/a><\/p>\n<p>La cercan\u00eda de Henr\u00edquez con el poder no se limitaba a los pasillos de la Asamblea Nacional o a las reuniones empresariales. Su presencia se extendi\u00f3 incluso a los viajes oficiales del entonces presidente Cortizo. Seg\u00fan consta en el detalle de viajes y vi\u00e1ticos publicados en el sitio oficial de la Presidencia, Henr\u00edquez form\u00f3 parte de la Misi\u00f3n Oficial a Texas en julio de 2021, cuyo objetivo, al menos en teor\u00eda, era atraer inversiones al pa\u00eds.<\/p>\n<p>En este periplo, el entonces yerno viaj\u00f3 como \u00abinvitado\u00bb, code\u00e1ndose con ministros, oficiales de protocolo y personal de seguridad.\u00a0Se consolida as\u00ed el retrato de un personaje que, pese a su maltrecha relaci\u00f3n con la hija del entonces mandatario, no perdi\u00f3 su acceso a las mieles del poder, sino que, al parecer, las aprovech\u00f3 para su propio beneficio y el de sus socios. La ley de incentivo fiscal, aprobada durante el gobierno de Laurentino Cortizo, y que benefici\u00f3 a magnates con una suma millonaria de d\u00f3lares, se erige como un monumento a una red de favores.<\/p>\n<h3>El legado Cortizo: Entre incentivos fiscales y secretos de familia<\/h3>\n<p><a class=\"thickbox\" href=\"https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2025\/03\/carolina-cortizo-juan-manuel-henriquez-novias.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-89776\" src=\"https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2025\/03\/carolina-cortizo-juan-manuel-henriquez-novias.jpg\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" srcset=\"https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2025\/03\/carolina-cortizo-juan-manuel-henriquez-novias.jpg 1200w, https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2025\/03\/1_carolina-cortizo-juan-manuel-henriquez-novias-300x193.jpg 300w, https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2025\/03\/1_carolina-cortizo-juan-manuel-henriquez-novias-1024x658.jpg 1024w, https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2025\/03\/1_carolina-cortizo-juan-manuel-henriquez-novias-768x493.jpg 768w, https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2025\/03\/carolina-cortizo-juan-manuel-henriquez-novias-150x96.jpg 150w, https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2025\/03\/carolina-cortizo-juan-manuel-henriquez-novias-650x418.jpg 650w, https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2025\/03\/carolina-cortizo-juan-manuel-henriquez-novias-400x257.jpg 400w, https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2025\/03\/carolina-cortizo-juan-manuel-henriquez-novias-250x161.jpg 250w\" alt=\"\" width=\"1200\" height=\"771\" \/><\/a><\/p>\n<p>El gobierno de Laurentino Cortizo quedar\u00e1 marcado, entre otras cosas, por la controvertida ley de incentivos fiscales al turismo. Una ley que, como se ha expuesto, benefici\u00f3 con m\u00e1s de 1.700 millones de d\u00f3lares a empresarios del sector, entre ellos, las familias Eleta y Bern, vinculadas a Juan Manuel Henr\u00edquez. Este \u00abregalo\u00bb del Estado, como algunos cr\u00edticos lo denominan, contrasta con la narrativa de un gobierno preocupado por el bienestar general.<\/p>\n<div id=\"attachment_92571\" class=\"wp-caption aligncenter\"><a class=\"thickbox\" title=\"Juan Manuel Henr\u00edquez\" href=\"https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2025\/03\/juan-manuel-henriquez-carolina-cortizo-6.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-92571\" src=\"https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2025\/03\/juan-manuel-henriquez-carolina-cortizo-6.jpg\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" srcset=\"https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2025\/03\/juan-manuel-henriquez-carolina-cortizo-6.jpg 1200w, https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2025\/03\/1_juan-manuel-henriquez-carolina-cortizo-6-300x209.jpg 300w, https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2025\/03\/juan-manuel-henriquez-carolina-cortizo-6-1024x714.jpg 1024w, https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2025\/03\/juan-manuel-henriquez-carolina-cortizo-6-768x536.jpg 768w, https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2025\/03\/juan-manuel-henriquez-carolina-cortizo-6-150x105.jpg 150w, https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2025\/03\/juan-manuel-henriquez-carolina-cortizo-6-650x453.jpg 650w, https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2025\/03\/juan-manuel-henriquez-carolina-cortizo-6-400x279.jpg 400w, https:\/\/www.ciudadgoticanews.com\/wp-content\/uploads\/2025\/03\/juan-manuel-henriquez-carolina-cortizo-6-250x174.jpg 250w\" alt=\"\" width=\"1200\" height=\"837\" aria-describedby=\"caption-attachment-92571\" \/><\/a><\/p>\n<p id=\"caption-attachment-92571\" class=\"wp-caption-text\">Juan Manuel Henr\u00edquez<\/p>\n<\/div>\n<p>El caso de Henr\u00edquez, el exyerno \u00absilenciado\u00bb y \u00abcompensado\u00bb, es solo una pieza del rompecabezas. Un ejemplo, quiz\u00e1s el m\u00e1s visible, de c\u00f3mo los intereses personales y familiares pueden entrelazarse con las decisiones pol\u00edticas, generando un ambiente de opacidad y sospecha. La historia de Carolina Cortizo, su matrimonio, su divorcio y su posterior compromiso con una mujer, es el tel\u00f3n de fondo de una trama mucho m\u00e1s compleja, donde el poder, el dinero y el silencio parecen tener un precio, pagadero con el erario p\u00fablico. La narrativa oficial hablaba de atraer inversiones y fomentar el turismo; la realidad, susurrada en los corrillos y publicada en algunos medios, sugiere una historia mucho m\u00e1s turbia y menos edificante.<\/p>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>(Fuente: Reporte de la Economia. Publicado el 20 de marzo de 2025) La ruptura matrimonial entre Carolina Cortizo Col\u00f3n, hija del expresidente paname\u00f1o Laurentino Cortizo (quien gobern\u00f3 Panam\u00e1 desde el 1 de julio de 2019 hasta el 30 de junio de 2024), y Juan Manuel Henr\u00edquez Portuondo, acaecida hace m\u00e1s de tres a\u00f1os, antes del [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":13222,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"h5ap_radio_sources":[],"footnotes":""},"categories":[29],"tags":[],"class_list":["post-13221","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-panama"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.ciudadgoticanews.com\/index.php\/wp-json\/wp\/v2\/posts\/13221","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ciudadgoticanews.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ciudadgoticanews.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ciudadgoticanews.com\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ciudadgoticanews.com\/index.php\/wp-json\/wp\/v2\/comments?post=13221"}],"version-history":[{"count":2,"href":"https:\/\/www.ciudadgoticanews.com\/index.php\/wp-json\/wp\/v2\/posts\/13221\/revisions"}],"predecessor-version":[{"id":13268,"href":"https:\/\/www.ciudadgoticanews.com\/index.php\/wp-json\/wp\/v2\/posts\/13221\/revisions\/13268"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ciudadgoticanews.com\/index.php\/wp-json\/wp\/v2\/media\/13222"}],"wp:attachment":[{"href":"https:\/\/www.ciudadgoticanews.com\/index.php\/wp-json\/wp\/v2\/media?parent=13221"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ciudadgoticanews.com\/index.php\/wp-json\/wp\/v2\/categories?post=13221"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ciudadgoticanews.com\/index.php\/wp-json\/wp\/v2\/tags?post=13221"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}