{"id":6371,"date":"2024-01-18T05:22:29","date_gmt":"2024-01-18T09:22:29","guid":{"rendered":"https:\/\/www.ciudadgoticanews.com\/?p=6371"},"modified":"2024-01-18T05:22:29","modified_gmt":"2024-01-18T09:22:29","slug":"la-trayectoria-de-omar-mora-tosta-de-la-defensa-de-mafias-en-caracas-a-la-del-equipo-politico-de-maria-corina-machado","status":"publish","type":"post","link":"https:\/\/www.ciudadgoticanews.com\/index.php\/2024\/01\/18\/la-trayectoria-de-omar-mora-tosta-de-la-defensa-de-mafias-en-caracas-a-la-del-equipo-politico-de-maria-corina-machado\/","title":{"rendered":"La trayectoria de Omar Mora Tosta: De la defensa de mafias en Caracas a la del equipo pol\u00edtico de Mar\u00eda Corina Machado"},"content":{"rendered":"<p>Miembros del partido pol\u00edtico Vente Venezuela, liderado por Mar\u00eda Corina Machado, han sido objeto de acusaciones judiciales recientes que los se\u00f1alan de traici\u00f3n a la patria y de conspirar con una potencia extranjera. Sin embargo, la defensa de estos dirigentes est\u00e1 en manos de un abogado que tiene un historial de v\u00ednculos con mafias y hechos il\u00edcitos: Omar Mora Tosta.<\/p>\n<h3>La acusaci\u00f3n del chavismo<\/h3>\n<p>Seg\u00fan el chavismo, los dirigentes de Vente Venezuela habr\u00edan mantenido una relaci\u00f3n con la empresa estadounidense Exxon Mobil, que explota el petr\u00f3leo en la zona del Esequibo, un territorio en disputa entre Venezuela y Guyana. Adem\u00e1s, habr\u00edan impulsado una campa\u00f1a para boicotear el refer\u00e9ndum que el r\u00e9gimen convoc\u00f3 el 3 de diciembre de 2023 para respaldar la reclamaci\u00f3n venezolana sobre ese territorio.<\/p>\n<p>Por estos motivos, el chavismo detuvo en diciembre de 2023 a varios miembros de Vente Venezuela y los imput\u00f3 por los delitos de traici\u00f3n a la patria, conspiraci\u00f3n con una potencia extranjera, legitimaci\u00f3n de capitales y asociaci\u00f3n para delinquir. Entre los detenidos se encuentran Henry Alviarez, coordinador nacional de organizaci\u00f3n; Claudia Macero, coordinadora de comunicaciones; Pedro Urruchurtu, coordinador de Asuntos Internacionales; y Roberto Abdul, co-fundador de la ONG S\u00famate, af\u00edn a Vente Venezuela. Posteriormente, los acusados fueron liberados con medidas cautelares de presentaci\u00f3n cada 15 d\u00edas ante los tribunales.<\/p>\n<blockquote class=\"twitter-tweet\" data-dnt=\"true\">\n<p dir=\"ltr\" lang=\"es\"><a href=\"https:\/\/twitter.com\/hashtag\/AhoraVPItv?src=hash&amp;ref_src=twsrc%5Etfw\">#AhoraVPItv<\/a> | Abog. Omar Mora Tosta se pronuncia sobre la presentaci\u00f3n del presidente de S\u00famate, Roberto Abdul, ante tribunales este lunes <a href=\"https:\/\/twitter.com\/hashtag\/15Ene?src=hash&amp;ref_src=twsrc%5Etfw\">#15Ene<\/a>.<\/p>\n<p>Con\u00e9ctate a nuestra se\u00f1al: <a href=\"https:\/\/t.co\/MArph6FEKc\">https:\/\/t.co\/MArph6FEKc<\/a> <a href=\"https:\/\/t.co\/AtiRImuIGm\">pic.twitter.com\/AtiRImuIGm<\/a><\/p>\n<p>\u2014 VPItv (@VPITV) <a href=\"https:\/\/twitter.com\/VPITV\/status\/1746961266130751872?ref_src=twsrc%5Etfw\">January 15, 2024<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<h3>La defensa de Omar Mora Tosta<\/h3>\n<p>El abogado penalista Omar Mora Tosta se ha encargado de defender a los dirigentes de Vente Venezuela ante la justicia chavista. Mora Tosta ha negado que sus defendidos sean culpables de los cargos que se les imputan y ha afirmado que no son agentes pol\u00edticos de Guyana. Asimismo, ha anunciado que en los pr\u00f3ximos d\u00edas se realizar\u00e1 la audiencia preliminar, en la que espera que se sobresea la causa por falta de pruebas de la supuesta conspiraci\u00f3n.<\/p>\n<p>Mora Tosta es un abogado con una larga y reconocida trayectoria en el \u00e1mbito penal. Ha defendido a algunos de los opositores m\u00e1s radicales a los gobiernos de Hugo Ch\u00e1vez y Nicol\u00e1s Maduro, como el general retirado Ra\u00fal Isa\u00edas Baduel, exministro de Ch\u00e1vez y luego disidente.<\/p>\n<h3>El pasado turbio de Mora Tosta<\/h3>\n<p>Sin embargo, el abogado tambi\u00e9n tiene un pasado oscuro que lo vincula con mafias y hechos il\u00edcitos. Mora Tosta fue, durante el segundo gobierno de Carlos Andr\u00e9s P\u00e9rez, antes de la llegada del chavismo, abogado de la consultor\u00eda jur\u00eddica y de la divisi\u00f3n antidrogas de la extinta DISIP, la polic\u00eda pol\u00edtica venezolana. En esa \u00e9poca, particip\u00f3 en la defensa de implicados en la llamada \u00abOperaci\u00f3n Norte\u00bb, que consist\u00eda en el traslado de coca\u00edna desde Venezuela a Estados Unidos bajo el pretexto de una operaci\u00f3n encubierta para desarticular una red de narcotr\u00e1fico. Mora Tosta se habr\u00eda ocupado de eliminar las evidencias que compromet\u00edan a funcionarios de la DISIP en ese caso.<\/p>\n<p>Adem\u00e1s, Mora se especializ\u00f3 en defender a las mafias de chiveras, que se dedicaban a la compra y venta de piezas de autos robados, especialmente en la zona de El Junquito, en las afueras de Caracas. Tambi\u00e9n defendi\u00f3 a los compradores de oro robado del Centro Comercial Ciudad Tamanaco (CCCT). Seg\u00fan se ha denunciado, Mora Tosta y su socio Ren\u00e9 Viso habr\u00edan desarrollado una pol\u00edtica para sobornar a jueces y fiscales. Mora Tosta tambi\u00e9n fue abogado de un comerciante apellidado Vitello, apodado \u00abchivatelli\u00bb, acusado de comprar piezas de autos robados. Muchas de sus estrategmas judiciales las habr\u00eda aprendido Mora cuando formaba parte del bufete de Mayra Vernet y Miguel Dao.<\/p>\n<p>Ante este panorama, algunos venezolanos se preguntan por qu\u00e9 Mar\u00eda Corina Machado y su equipo pol\u00edtico han escogido a un abogado con este tipo de antecedentes para defenderlos. \u00bfNo hay otros profesionales de la abogac\u00eda con mejor reputaci\u00f3n en Venezuela? \u00bfQu\u00e9 intereses hay detr\u00e1s de esta decisi\u00f3n? \u00bfQu\u00e9 imagen proyecta Vente Venezuela al rodearse de personajes y abogados que en el pasado han defendido a mafias?<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Miembros del partido pol\u00edtico Vente Venezuela, liderado por Mar\u00eda Corina Machado, han sido objeto de acusaciones judiciales recientes que los se\u00f1alan de traici\u00f3n a la patria y de conspirar con una potencia extranjera. Sin embargo, la defensa de estos dirigentes est\u00e1 en manos de un abogado que tiene un historial de v\u00ednculos con mafias y [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":6374,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"h5ap_radio_sources":[],"footnotes":""},"categories":[9],"tags":[],"class_list":["post-6371","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-venezuela"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.ciudadgoticanews.com\/index.php\/wp-json\/wp\/v2\/posts\/6371","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ciudadgoticanews.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ciudadgoticanews.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ciudadgoticanews.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ciudadgoticanews.com\/index.php\/wp-json\/wp\/v2\/comments?post=6371"}],"version-history":[{"count":0,"href":"https:\/\/www.ciudadgoticanews.com\/index.php\/wp-json\/wp\/v2\/posts\/6371\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ciudadgoticanews.com\/index.php\/wp-json\/wp\/v2\/media\/6374"}],"wp:attachment":[{"href":"https:\/\/www.ciudadgoticanews.com\/index.php\/wp-json\/wp\/v2\/media?parent=6371"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ciudadgoticanews.com\/index.php\/wp-json\/wp\/v2\/categories?post=6371"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ciudadgoticanews.com\/index.php\/wp-json\/wp\/v2\/tags?post=6371"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}